{"id":63410,"date":"2025-09-04T13:35:44","date_gmt":"2025-09-04T11:35:44","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=63410"},"modified":"2025-09-04T14:19:32","modified_gmt":"2025-09-04T12:19:32","slug":"a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/","title":{"rendered":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em 8 de setembro de 2025, a <a href=\"https:\/\/schoenstatt.com\/pt-pt\/em-comunidade\/woman\/uniao-de-maes\/\">Uni\u00e3o Apost\u00f3lica Internacional das M\u00e3es de Schoenstatt<\/a> comemora a Natividade da Virgem Maria e os 75 anos de funda\u00e7\u00e3o da comunidade internacional, bem como no seu local de nascimento, a Alemanha. \u00c9 um marco significativo na hist\u00f3ria de Schoenstatt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir da Liga Apost\u00f3lica, por volta de 1946, havia grupos de mulheres na diocese alem\u00e3, incluindo m\u00e3es casadas e vi\u00favas, que se reuniam para colaborar na busca por um estilo de vida pr\u00f3prio. O Pe. Jos\u00e9 Kentenich reconheceu esse grande anseio e, ap\u00f3s discuti-lo com as mulheres, organizou um retiro de 4 a 8 de setembro de 1950 para o c\u00edrculo de lideran\u00e7a das m\u00e3es. A Sra. Maria Maud Wiesmann, representante das l\u00edderes diocesanas, informou o fundador sobre a situa\u00e7\u00e3o delas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o retiro, ap\u00f3s ouvir as palestras do Pai, a Uni\u00e3o das M\u00e3es na Alemanha, enraizada na Alian\u00e7a de Amor, foi fundada em 8 de setembro de 1950, conforme previsto pelo Pe. Kentenich. Ele afirmou, em seu discurso de encerramento (J.K.: Uns gesagt Vol. 3, p. 130):<\/p>\n\n\n\n<figure class=\"wp-block-pullquote has-medium-font-size\" style=\"border-top-color:var(--wp--preset--color--luminous-vivid-orange);border-top-style:solid;border-top-width:1px;border-bottom-color:var(--wp--preset--color--luminous-vivid-orange);border-bottom-style:solid;border-bottom-width:1px;font-style:italic;font-weight:300\"><blockquote><p>\u201cDepois de tudo o que surgiu (em Schoenstatt), agora temos um curso de Uni\u00e3o na obra das M\u00e3es. \u2026 Se a Uni\u00e3o foi concretizada aqui, ela tamb\u00e9m deve surgir no exterior.\u201d (Ibid., p. 141.)<\/p><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-novos-cursos-ganham-vida\">Novos cursos ganham vida<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Com grande anseio e fidelidade, durante o ex\u00edlio do Padre Kentenich, foram criados seis cursos, e sua consagra\u00e7\u00e3o na Uni\u00e3o foi selada no mesmo esp\u00edrito da Uni\u00e3o Apost\u00f3lica original. As m\u00e3es reconheceram sua responsabilidade de formar uma base s\u00f3lida para um maior desenvolvimento e permaneceram fi\u00e9is ao seu fundador. Ap\u00f3s seu retorno de Milwaukee, o Pai considerou a experi\u00eancia da Uni\u00e3o das M\u00e3es um sucesso e encarregou a Ir. M. Vita Gro\u00dfmann e o Pe. Rudolph Mosbach de elaborar os estatutos em conjunto com as m\u00e3es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assumindo a tarefa do fundador, ap\u00f3s ele ter falecido, o Pe. Alexander Menningen seguiu com a constitui\u00e7\u00e3o da Uni\u00e3o das M\u00e3es na Alemanha em 22 de agosto de 1970. A Comunidade Oficial surgiu, dividida em cinco regi\u00f5es que, juntamente com a comunidade central, concretizaram o princ\u00edpio da tens\u00e3o criadora idealizado pelo Pai.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-um-importante-passo-internacional\">Um importante passo internacional<\/h3>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/06\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Encontro em 2022<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em 8 de setembro de 2022, Deus Pai iniciou uma nova iniciativa divina e, com Maria, deu origem \u00e0 Uni\u00e3o Apost\u00f3lica Internacional das M\u00e3es de Schoenstatt, uma comunidade central dentro da Fam\u00edlia de Schoenstatt. Globalmente, tamb\u00e9m celebramos essa data, marcando o terceiro anivers\u00e1rio de nossa funda\u00e7\u00e3o, um marco significativo no desenvolvimento da Uni\u00e3o das M\u00e3es. A Uni\u00e3o foi criada, com seu cap\u00edtulo fundador origin\u00e1rio da Alemanha. Ela cumpriu o desejo do Pe. Jos\u00e9 Kentenich de que muitas mulheres e m\u00e3es se tornassem \u201cuma pequena Maria\u201d; uma realidade que se reflete no surgimento de comunidades da Uni\u00e3o das M\u00e3es em v\u00e1rios pa\u00edses, incluindo Argentina, Brasil, Chile, Estados Unidos, Paraguai, Portugal, \u00c1frica do Sul, Su\u00ed\u00e7a, Espanha e Costa Rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como comunidade da Uni\u00e3o das M\u00e3es, composta por mulheres casadas, m\u00e3es e esposas, com ou sem filhos, somos chamadas a ver nosso ideal na pessoa e na miss\u00e3o de Maria, a M\u00e3e de Deus \u2014 um reflexo de nossos tempos \u2014 em nossas fam\u00edlias, igrejas e sociedade. Nossa lideran\u00e7a \u00e9 guiada pelos princ\u00edpios de Schoenstatt, que enfatizam a generosidade e a liberdade interior, de acordo com o Magist\u00e9rio da Igreja, servindo como base para nossa vida conjugal e familiar. Al\u00e9m disso, um alto grau de cultivo do esp\u00edrito na Alian\u00e7a de Amor \u00e9 nossa fonte de for\u00e7a e inspira\u00e7\u00e3o, guiando nossa vis\u00e3o da humanidade que buscamos realizar em nossas pr\u00f3prias vidas e atrav\u00e9s de nossa miss\u00e3o compartilhada de trabalhar uns com os outros e uns pelos outros. Encontramos um lema comum atrav\u00e9s do di\u00e1logo construtivo e do respeito pela originalidade de cada pa\u00eds: \u201cMaria, quem me olhar, te veja!\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-olhar-ao-futuro\">Olhar ao futuro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como Uni\u00e3o das M\u00e3es, nossa esperan\u00e7a e miss\u00e3o s\u00e3o estabelecer uma rede internacional e intercultural de territ\u00f3rios aut\u00f4nomos, promovendo a unidade na diversidade e trabalhando em benef\u00edcio das fam\u00edlias e das mulheres em todo o mundo. Nossos esfor\u00e7os est\u00e3o enraizados nas origens da Uni\u00e3o das M\u00e3es da Alemanha e s\u00e3o realizados atrav\u00e9s do estabelecimento de uma rede global que nos conecta atrav\u00e9s de diferentes culturas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/10\/uniao-de-maes-costa-rica-federacion-de-madres-mother-federation-schoenstatt-2-1.jpg\" alt=\"\" class=\"wp-image-42126\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/10\/uniao-de-maes-costa-rica-federacion-de-madres-mother-federation-schoenstatt-2-1.jpg 1600w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/10\/uniao-de-maes-costa-rica-federacion-de-madres-mother-federation-schoenstatt-2-1-768x576.jpg 768w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/10\/uniao-de-maes-costa-rica-federacion-de-madres-mother-federation-schoenstatt-2-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-element-caption\">Primeiro Curso da comunidade na Costa Rica<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Uni\u00e3o Internacional das M\u00e3es celebra 75 anos com alegria e gratid\u00e3o pela gera\u00e7\u00e3o fundadora, cuja f\u00e9 e esperan\u00e7a, em 8 de setembro de 1950, nosso dia de funda\u00e7\u00e3o, nos aben\u00e7oaram e guiaram em nossa heran\u00e7a comum como irm\u00e3s e filhas do mesmo Pai, independentemente da l\u00edngua ou da dist\u00e2ncia que possa nos separar. Por meio da instrumentalidade, estamos cumprindo a tarefa que Maria nos confiou. Estamos comprometidas com o carisma e a miss\u00e3o do Fundador com um esp\u00edrito apost\u00f3lico universal, onde a filialidade est\u00e1 no centro, tanto pessoalmente quanto dentro da comunidade. Formamos a pars motrix (parte central) da Obra de Schoenstatt junto com os institutos e outras Uni\u00f5es. \u00c9 a obra da M\u00e3e de Deus; \u00e9 ela quem nos convida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u201cMaria, quem me olhar, te veja<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kathleen Colunga<br>Dirigente Internacional<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.<\/p>\n","protected":false},"author":3,"featured_media":63395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[908],"tags":[],"class_list":["post-63410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-de-schoenstatt-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos - Schoenstatt<\/title>\n<meta name=\"description\" content=\"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos\" \/>\n<meta property=\"og:description\" content=\"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T11:35:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T12:19:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos\",\"datePublished\":\"2025-09-04T11:35:44+00:00\",\"dateModified\":\"2025-09-04T12:19:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/\"},\"wordCount\":929,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp\",\"articleSection\":[\"Comunidades de Schoenstatt\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/\",\"name\":\"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp\",\"datePublished\":\"2025-09-04T11:35:44+00:00\",\"dateModified\":\"2025-09-04T12:19:32+00:00\",\"description\":\"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp\",\"width\":2048,\"height\":1154},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos - Schoenstatt","description":"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/","og_locale":"pt_PT","og_type":"article","og_title":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos","og_description":"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.","og_url":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/","og_site_name":"Schoenstatt","article_published_time":"2025-09-04T11:35:44+00:00","article_modified_time":"2025-09-04T12:19:32+00:00","og_image":[{"width":2048,"height":1154,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos","datePublished":"2025-09-04T11:35:44+00:00","dateModified":"2025-09-04T12:19:32+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/"},"wordCount":929,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp","articleSection":["Comunidades de Schoenstatt"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/","url":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/","name":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp","datePublished":"2025-09-04T11:35:44+00:00","dateModified":"2025-09-04T12:19:32+00:00","description":"No pr\u00f3ximo dia 8 de setembro, a Uni\u00e3o de M\u00e3es de Schoenstatt completa 75 anos de funda\u00e7\u00e3o, uma hist\u00f3ria de gra\u00e7as especiais.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/federacion-madres-uniao-de-maes-mutterbund-schoenstatt.webp","width":2048,"height":1154},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/a-uniao-das-maes-de-schoenstatt-vai-comemorar-75-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"A Uni\u00e3o das M\u00e3es de Schoenstatt vai comemorar 75 anos"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=63410"}],"version-history":[{"count":7,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63410\/revisions"}],"predecessor-version":[{"id":63418,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63410\/revisions\/63418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/63395"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=63410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=63410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=63410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}