{"id":50742,"date":"2022-10-19T14:21:10","date_gmt":"2022-10-19T12:21:10","guid":{"rendered":"https:\/\/schoenstattdev.wpenginepowered.com\/?p=27379"},"modified":"2025-05-16T01:30:56","modified_gmt":"2025-05-15T23:30:56","slug":"juventude-feminina-do-mexico-se-reune-em-jornada-nacional","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/","title":{"rendered":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional"},"content":{"rendered":"<h3>REGINAE SUM &#8211; PERTEN\u00c7O \u00c0 RAINHA<\/h3>\n<p>No fim de semana de 7 a 9 de outubro,<a href=\"https:\/\/schoenstattdev.wpenginepowered.com\/pt-pt\/familia\/comunidades-do-movimento-apostolico-de-schoenstatt\/woman\/\"> 156 meninas<\/a> se reuniram \u00e0 sombra do Santu\u00e1rio &#8220;<em>Cora\u00e7\u00e3o Fiel da Igreja<\/em>&#8221; em Quer\u00e9taro para a Jornada Nacional da Juventude Feminina do M\u00e9xico 2022.<\/p>\n<p>Representantes de dez estados (Chiapas, Iguala, Taxco, Quer\u00e9taro, Le\u00f3n, Aguascalientes, Guadalajara, Monclova, Monterrey e Chihuahua) fizeram parte deste primeiro encontro nacional presencial da JF, desde o come\u00e7o da pandemia.<\/p>\n<p>O lema central da Jornada foi: &#8220;<em><strong>Reginae Sum<\/strong><\/em>&#8221; \u2013 Perten\u00e7o \u00e0 Rainha \u2013 \u200b\u200be todos os temas e atividades ajudaram as meninas a aprofundar o significado desta grande verdade: serem as filhas prediletas da Rainha e do Rei, e o dever de proclamar esta verdade com a vida.<\/p>\n<h3>Oficinas sobre a fidelidade, a nobreza, o amor e a confian\u00e7a<\/h3>\n<p>O programa de atividades incluiu oficinas sobre a fidelidade, a nobreza, o amor, a confian\u00e7a e a autenticidade. Houve tamb\u00e9m piqueniques de discuss\u00e3o, momentos de ora\u00e7\u00e3o, Santa Missa, cantos, din\u00e2micas, uma reuni\u00e3o noturna e a tradicional festa mariana, preparada por representantes dos diferentes estados em honra a Maria.<\/p>\n<p>O momento culminante da Jornada Nacional foi a coroa\u00e7\u00e3o da M\u00e3e Sant\u00edssima com uma coroa RTA feita pelas meninas. Os diferentes estados tiveram a oportunidade de conquistar um peda\u00e7o da coroa com suas contribui\u00e7\u00f5es para o capital de gra\u00e7as. Junto com a coroa, cada participante tamb\u00e9m p\u00f4de entregar \u00e0 M\u00e3e Sant\u00edssima seus sonhos, desejos e inten\u00e7\u00f5es.<\/p>\n<h3>Consci\u00eancia da nossa nobreza, dignidade e de estarmos acolhidas<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-27353 size-large\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-3-2-1024x768.jpeg\" alt=\"Juventude Feminina\" width=\"840\" height=\"630\" \/><\/p>\n<p>Ao mesmo tempo, cinquenta jovens coroaram seu cetro de l\u00edrio como s\u00edmbolo de sua perten\u00e7a \u00e0 M\u00e3e Sant\u00edssima e de seu compromisso de lutar para viver o ideal nacional de ser &#8220;Como filha imaculada, instrumento do Pai&#8221;. Depois de coroar a M\u00e3e Sant\u00edssima, cada uma recebeu um broche da RTA*, que lembra a coroa que Maria apresenta a seus filhos e filhas quando a coroam: \u201c<em>\u2026quando n\u00f3s a coroamos, ent\u00e3o ela tamb\u00e9m nos d\u00e1 uma coroa, e com esta coroa, a consci\u00eancia da nossa nobreza, da nossa grandeza, mas tamb\u00e9m a consci\u00eancia de estarmos protegidos e de nos sentirmos acolhidos<\/em>\u201d (P. Jos\u00e9 Kentenich).<\/p>\n<p>Cada jovem trocou sua coroa com uma de suas companheiras, reconhecendo n\u00e3o s\u00f3 a sua pr\u00f3pria dignidade, mas tamb\u00e9m a das demais. A alegria e as gra\u00e7as deste momento foram muito tang\u00edveis! Para terminar o dia, celebramos a Rainha com um jantar de gala e bailes, seguido de uma vig\u00edlia noturna de adora\u00e7\u00e3o no Santu\u00e1rio.<\/p>\n<h3>Anseio do Pai, acende no amor<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-27357 size-large\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1024x766.jpeg\" alt=\"\" width=\"840\" height=\"628\" \/><\/p>\n<p>No dia seguinte, foi revelado o novo lema que guiar\u00e1 e inspirar\u00e1 o ramo nos pr\u00f3ximos dois anos: <em><strong>&#8220;Anseio do Pai, acende no amor!&#8221;<\/strong><\/em>\u00a0 Com este lema, a M\u00e3e Sant\u00edssima chama sua Juventude Feminina Mexicana a viver profundamente convencidas de serem filhas prediletas de Deus Pai. Desde toda a eternidade, o Pai concebeu cada ser humano, tal como ele \u00e9, com seus talentos e fraquezas, com sua originalidade, e agora, Ele anseia que cumpramos a miss\u00e3o pessoal que nos confiou e que sejamos portadoras de sua promessa ao mundo. O anseio do Pai \u00e9 que nos acendamos mutuamente no amor, que reconhe\u00e7amos nossa dignidade de filhas e que, atrav\u00e9s do nosso ser, respondamos \u00e0s muitas necessidades do mundo de hoje.<\/p>\n<p>A Jornada terminou com uma ora\u00e7\u00e3o de envio que rezamos juntas em frente \u00e0 imagem da Imaculada Concei\u00e7\u00e3o, que nos acompanhou durante todo o encontro, lembrando-nos da grandeza do ideal de ser, como mulheres aut\u00eanticas, pequenos reflexos de Maria para o mundo.<\/p>\n<blockquote><p>Como filha imaculada, instrumento do Pai!<\/p>\n<p>Uma \u00fanica miss\u00e3o \u2013 uma \u00fanica bandeira.<\/p>\n<p>Um \u00fanico amor \u2013 um Cetro de L\u00edrio.<\/p>\n<p>Uma \u00fanica coroa \u2013 um \u00fanico trono.<\/p>\n<p>Um \u00fanico Rei e uma \u00fanica Rainha acima de todas as coisas.<\/p>\n<p>Coroa por coroa! Permanecemos nisso, permanecemos fi\u00e9is.<\/p>\n<p>Coroa por coroa.<\/p><\/blockquote>\n<p>* RTA s\u00e3o as iniciais de Regina Ter Admirabilis, em espanhol: Reina Tres Veces Admirable, expressando o car\u00e1ter rainha de Nossa Senhora de Schoenstatt, M\u00e3e Tr\u00eas Vezes Admir\u00e1vel \u2013 MTA \u2013.<\/p>\n<p>Para conhecer a hist\u00f3ria da coroa RTA pode ser acessado atrav\u00e9s do seguinte link:<\/p>\n<p><iframe title=\"Historia JF internacional - Corona RTA\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/uQBBxm5j07M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Juventude Feminina do M\u00e9xico teve sua jornada anual de dirigentes, no qual aprofundou seu ideal: &#8220;Reginae sum &#8211; Perten\u00e7o \u00e0 Rainha&#8221;, que as levou a mergulhar no valor de ter Maria como rainha, que transmite a suas aliadas a dignidade dos filhos de Deus, da sua nobreza, despertando a voca\u00e7\u00e3o a ser testemunhos de amor.<\/p>\n","protected":false},"author":1,"featured_media":27349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[636,665],"tags":[],"class_list":["post-50742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-pt-pt","category-juventude-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional - Schoenstatt<\/title>\n<meta name=\"description\" content=\"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional\" \/>\n<meta property=\"og:description\" content=\"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T12:21:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T23:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/489465b1850e7b216fe2c10dfc262551\"},\"headline\":\"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional\",\"datePublished\":\"2022-10-19T12:21:10+00:00\",\"dateModified\":\"2025-05-15T23:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/\"},\"wordCount\":730,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg\",\"articleSection\":[\"Eventos\",\"Juventude\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/\",\"name\":\"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg\",\"datePublished\":\"2022-10-19T12:21:10+00:00\",\"dateModified\":\"2025-05-15T23:30:56+00:00\",\"description\":\"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg\",\"width\":1024,\"height\":768,\"caption\":\"Girls' Youth\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/489465b1850e7b216fe2c10dfc262551\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/schoenstatt.com\"],\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional - Schoenstatt","description":"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/","og_locale":"pt_PT","og_type":"article","og_title":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional","og_description":"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.","og_url":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/","og_site_name":"Schoenstatt","article_published_time":"2022-10-19T12:21:10+00:00","article_modified_time":"2025-05-15T23:30:56+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/"},"author":{"name":"admin","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/489465b1850e7b216fe2c10dfc262551"},"headline":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional","datePublished":"2022-10-19T12:21:10+00:00","dateModified":"2025-05-15T23:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/"},"wordCount":730,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg","articleSection":["Eventos","Juventude"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/","url":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/","name":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg","datePublished":"2022-10-19T12:21:10+00:00","dateModified":"2025-05-15T23:30:56+00:00","description":"156 jovens participaram da Jornada Nacional da Juventude Feminina do M\u00e9xico e reafirmaram seu ideal Reginae sum - Perten\u00e7o \u00e0 Rainha.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-08.54.19-1-1.jpeg","width":1024,"height":768,"caption":"Girls' Youth"},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/juventude-feminina-do-mexico-se-reune-em-jornada-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"Juventude Feminina do M\u00e9xico se re\u00fane em jornada nacional"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/489465b1850e7b216fe2c10dfc262551","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/schoenstatt.com"],"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=50742"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50742\/revisions"}],"predecessor-version":[{"id":50886,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50742\/revisions\/50886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/27349"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=50742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=50742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=50742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}