{"id":50113,"date":"2023-01-18T08:00:38","date_gmt":"2023-01-18T07:00:38","guid":{"rendered":"https:\/\/schoenstattdev.wpenginepowered.com\/?p=28993"},"modified":"2025-05-16T00:31:17","modified_gmt":"2025-05-15T22:31:17","slug":"sabe-de-onde-vem-a-oracao-da-pequena-consagracao","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/","title":{"rendered":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?"},"content":{"rendered":"<p>Em Schoenstatt estamos muito acostumados a rezar a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o todos os dias.\u00a0 No dia 18 de cada m\u00eas \u00e9 muito importante para n\u00f3s renovarmos com especial devo\u00e7\u00e3o a nossa consagra\u00e7\u00e3o a Maria, e o fazemos rezando, individualmente ou na celebra\u00e7\u00e3o da renova\u00e7\u00e3o da Alian\u00e7a, a pequena consagra\u00e7\u00e3o e com ela entregamos novamente a Maria tudo o que somos e temos.<\/p>\n<p><em>Mas alguma vez j\u00e1 nos perguntamos de onde vem essa ora\u00e7\u00e3o?<\/em><\/p>\n<h3>Contexto hist\u00f3rico da &#8220;Pequena Consagra\u00e7\u00e3o&#8221;<\/h3>\n<p>Muitas das ora\u00e7\u00f5es de devo\u00e7\u00e3o popular correspondem a antigas tradi\u00e7\u00f5es que se conservaram dentro da Igreja e cuja origem costuma ser desconhecida, mas que foram incorporadas e respeitadas pelo povo cat\u00f3lico como pr\u00f3prias.\u00a0 \u00c9 o caso da Pequena Consagra\u00e7\u00e3o a Maria.<\/p>\n<p>Esta ora\u00e7\u00e3o, tamb\u00e9m conhecida como &#8220;Oh, minha senhora&#8221;, acredita-se que tenha sido composta por volta do s\u00e9culo XVI.\u00a0 Nela se expressam alguns elementos b\u00e1sicos da espiritualidade mariana.<\/p>\n<p>Recordemos que no s\u00e9culo XVI a Europa se encontrava na transi\u00e7\u00e3o entre a Idade M\u00e9dia e o Renascimento.\u00a0 A vassalagem era a forma t\u00edpica de pertencer \u00e0 sociedade.\u00a0 Todos os homens e suas fam\u00edlias pertenciam a um senhor.\u00a0 N\u00e3o era uma perten\u00e7a estabelecida por lei, mas baseada no que se chamava de v\u00ednculo de depend\u00eancia.<\/p>\n<p>Esse v\u00ednculo consistia fundamentalmente em uma ades\u00e3o m\u00fatua entre senhor e vassalo com base na fidelidade e na honra.\u00a0 O senhor se comprometia a resguardar, proteger e alimentar o seu vassalo, pois ele era um membro de sua tropa, e o vassalo, por sua vez, se comprometia a n\u00e3o ter nem servir a ningu\u00e9m que n\u00e3o fosse o seu senhor, ao lado de quem devia lutar.<\/p>\n<p>Esta forma de relacionamento dava origem a uma uni\u00e3o fraterno-filial, de depend\u00eancia e solidariedade de destinos.\u00a0 O destino de um dependia do destino do outro.\u00a0 Se estabelecia assim, uma forma de alian\u00e7a para proteger e defender uns aos outros.\u00a0 A forma mais marcante desse v\u00ednculo entre senhor e vassalo era o juramento de sangue, quando eram de alta linhagem, pelo qual ambos prometiam dar a vida um pelo outro, se fosse necess\u00e1rio.<\/p>\n<h3>Ora\u00e7\u00e3o oficial das Congrega\u00e7\u00f5es Marianas<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-28968 size-large\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/sr.cacilda_DSC4795-1.jpg\" alt=\"Pequena Consagra\u00e7\u00e3o\" width=\"840\" height=\"471\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/sr.cacilda_DSC4795-1.jpg 1280w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/sr.cacilda_DSC4795-1-768x431.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/p>\n<p>Mais tarde, a Pequena Consagra\u00e7\u00e3o tornou-se a ora\u00e7\u00e3o oficial das Congrega\u00e7\u00f5es Marianas nascidas sob a prote\u00e7\u00e3o da Companhia de Jesus.\u00a0 \u00c9 por este caminho que chegou a Schoenstatt.\u00a0 Lembremos que na origem de Schoenstatt est\u00e1 a funda\u00e7\u00e3o da Congrega\u00e7\u00e3o Mariana, dependente de Ingolstadt, na Baviera.<\/p>\n<p>Tamb\u00e9m outras comunidades marianas da Igreja costumam rezar a Pequena Consagra\u00e7\u00e3o, que est\u00e1 amplamente difundida entre o povo cat\u00f3lico.<\/p>\n<h3>Nossa vida de alian\u00e7a segundo a Pequena Consagra\u00e7\u00e3o<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-28964 size-large\" src=\"https:\/\/schoenstattdev.wpenginepowered.com\/wp-content\/uploads\/2023\/01\/IMG_0185-1024x768.jpg\" alt=\"\" width=\"840\" height=\"630\" \/><\/p>\n<p>Rezar a pequena consagra\u00e7\u00e3o todos os dias deve ter um efeito na minha vida di\u00e1ria.\u00a0 Ao entregar-me a Maria, devo tornar-me cada vez mais semelhante a ela.<\/p>\n<p>Iniciamos a nossa ora\u00e7\u00e3o chamando Maria Sant\u00edssima: <em>&#8220;Minha Senhora&#8221; e &#8220;Minha M\u00e3e&#8221;.<\/em>\u00a0 Ao dizer<em> &#8220;Senhora&#8221;<\/em>, reconhecemos sua realeza e seu poder.\u00a0 Ela \u00e9 nossa Rainha junto com Cristo Rei.\u00a0 Mas \u00e9 tamb\u00e9m nossa M\u00e3e, uma M\u00e3e que tem o poder de Rainha, porque o Senhor o colocou nas suas m\u00e3os, para que ela possa cumprir a miss\u00e3o que Ele lhe confiou do alto da cruz.\u00a0 \u00c9 uma Rainha que \u00e9 M\u00e3e, que est\u00e1 investida do poder do amor e da miseric\u00f3rdia.<\/p>\n<p><a href=\"https:\/\/schoenstattdev.wpenginepowered.com\/pt-pt\/espiritualidade\/preparamos-a-alianca-de-amor-virtualmente-gracas-a-pandemia\/\">A alian\u00e7a de amor<\/a> selada com Maria nos faz sentir pr\u00f3ximos dela, muito pr\u00f3ximos do nosso cora\u00e7\u00e3o.\u00a0 Ao dizer <em>&#8220;Senhora e Minha M\u00e3e&#8221;,<\/em> sabemos que ela nos contempla com carinho maternal e que, em resposta, tamb\u00e9m nos diz:<em> &#8220;Meu filho, sim, sou sua M\u00e3e e sua Rainha, e voc\u00ea \u00e9 meu filho amado, minha filha amada&#8221;<\/em>.<\/p>\n<p>Como n\u00f3s a amamos, brota em nosso cora\u00e7\u00e3o um: <em>&#8220;Eu me ofere\u00e7o todo a v\u00f3s<\/em>&#8220;.\u00a0 \u00c9 uma express\u00e3o espont\u00e2nea de entrega.<\/p>\n<p>O amor n\u00e3o se contenta em dar uma parte, apenas algo pr\u00f3prio.\u00a0 O amor verdadeiro tudo entrega, se oferece e se doa por inteiro.<\/p>\n<h3>Tr\u00eas verbos<\/h3>\n<p><img decoding=\"async\" class=\"alignleft wp-image-28972 size-medium\" src=\"https:\/\/schoenstattdev.wpenginepowered.com\/wp-content\/uploads\/2023\/01\/SA-003-300x225.jpg\" alt=\"Pequena Consagra\u00e7\u00e3o\" width=\"300\" height=\"225\" \/><\/p>\n<p>Por \u00faltimo, tr\u00eas verbos.\u00a0 Pedimos a Maria tr\u00eas coisas:<em><strong> que cuide de n\u00f3s, que nos defenda e que nos use<\/strong><\/em>.\u00a0 N\u00e3o duvidamos por um momento que nos guarda e cuida de n\u00f3s, e que nos defende a cada momento de todas as dificuldades.\u00a0 E o terceiro verbo \u00e9 aquele que nos d\u00e1 o voo, um voo de liberdade e dignidade, porque pedimos \u00e0 nossa M\u00e3e que use este pequeno instrumento que cada um de n\u00f3s somos, para as suas pequenas e grandes conquistas. Desde o momento em que nos levantamos at\u00e9 a hora de dormir, nos sentimos como seus instrumentos, para em cada detalhe, mudar nossos cora\u00e7\u00f5es, nossas fam\u00edlias, nosso ambiente, e assim sermos instrumentos para mudar o mundo.\u00a0 O que mais podemos pedir, do que ser instrumentos para a maior miss\u00e3o do universo?<\/p>\n<p>E agora te convido a rezar a pequena consagra\u00e7\u00e3o com profunda consci\u00eancia do seu significado.<\/p>\n<blockquote><p>Oh minha senhora, oh minha m\u00e3e,<\/p>\n<p>Eu me ofere\u00e7o todo a v\u00f3s<\/p>\n<p>e em prova da minha devo\u00e7\u00e3o para convosco,<\/p>\n<p>Eu te consagro neste dia<\/p>\n<p>os meus olhos, os meus ouvidos, a minha boca, o meu cora\u00e7\u00e3o;<\/p>\n<p>e inteiramente todo o meu ser.<\/p>\n<p>E porque assim sou vosso, \u00f3 incompar\u00e1vel M\u00e3e,<\/p>\n<p>guardai-me, defendei-me<\/p>\n<p>como seu coisa e propriedade vossa,<\/p>\n<p>Am\u00e9m.<\/p><\/blockquote>\n<p>Fonte: A Alian\u00e7a de Amor com Maria, Padre Rafael Fern\u00e1ndez, Editorial Patris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ora\u00e7\u00e3o que mais representa Schoenstatt \u00e9 a da Pequena Consagra\u00e7\u00e3o.  De forma muito singela, ela resume todo o conte\u00fado da Alian\u00e7a de Amor. Compartilhamos aqui brevemente suas origens e seu significado.<\/p>\n","protected":false},"author":1,"featured_media":28984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[916],"tags":[],"class_list":["post-50113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidade-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o? - Schoenstatt<\/title>\n<meta name=\"description\" content=\"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?\" \/>\n<meta property=\"og:description\" content=\"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-18T07:00:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T22:31:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1895\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/489465b1850e7b216fe2c10dfc262551\"},\"headline\":\"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?\",\"datePublished\":\"2023-01-18T07:00:38+00:00\",\"dateModified\":\"2025-05-15T22:31:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/\"},\"wordCount\":952,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-1243-scaled-1.jpg\",\"articleSection\":[\"Espiritualidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/\",\"name\":\"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o? - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-1243-scaled-1.jpg\",\"datePublished\":\"2023-01-18T07:00:38+00:00\",\"dateModified\":\"2025-05-15T22:31:17+00:00\",\"description\":\"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-1243-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-1243-scaled-1.jpg\",\"width\":2560,\"height\":1895,\"caption\":\"Pequena Consagra\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/489465b1850e7b216fe2c10dfc262551\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/schoenstatt.com\"],\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o? - Schoenstatt","description":"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/","og_locale":"pt_PT","og_type":"article","og_title":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?","og_description":"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.","og_url":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/","og_site_name":"Schoenstatt","article_published_time":"2023-01-18T07:00:38+00:00","article_modified_time":"2025-05-15T22:31:17+00:00","og_image":[{"width":2560,"height":1895,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/"},"author":{"name":"admin","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/489465b1850e7b216fe2c10dfc262551"},"headline":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?","datePublished":"2023-01-18T07:00:38+00:00","dateModified":"2025-05-15T22:31:17+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/"},"wordCount":952,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg","articleSection":["Espiritualidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/","url":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/","name":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o? - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg","datePublished":"2023-01-18T07:00:38+00:00","dateModified":"2025-05-15T22:31:17+00:00","description":"Na ora\u00e7\u00e3o da Pequena Consagra\u00e7\u00e3o se resume o mist\u00e9rio da Alian\u00e7a de Amor, com uma poesia que motiva a entrega m\u00fatua de cora\u00e7\u00f5es.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/01\/IMG-1243-scaled-1.jpg","width":2560,"height":1895,"caption":"Pequena Consagra\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/sabe-de-onde-vem-a-oracao-da-pequena-consagracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"Sabe de onde vem a ora\u00e7\u00e3o da pequena consagra\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/489465b1850e7b216fe2c10dfc262551","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02e8345e1ec40ab0e0a2a98fdde64a684bbaf994cddcb778b25b8b024ee9dfe6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/schoenstatt.com"],"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=50113"}],"version-history":[{"count":2,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50113\/revisions"}],"predecessor-version":[{"id":55924,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50113\/revisions\/55924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/28984"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=50113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=50113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=50113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}