{"id":43400,"date":"2025-02-14T03:03:00","date_gmt":"2025-02-14T02:03:00","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=43400"},"modified":"2025-08-18T20:22:05","modified_gmt":"2025-08-18T18:22:05","slug":"festa-de-sao-valentim-do-amor-liquido-ao-amor-agape","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/","title":{"rendered":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u00e1 pelo s\u00e9culo III d.C., o imperador romano Cl\u00e1udio II proibiu seus soldados de se casarem com mo\u00e7as crist\u00e3s. Al\u00e9m de sua oposi\u00e7\u00e3o ao cristianismo, o governante estava convencido de que os homens solteiros e \u201csem ataduras\u201d eram os melhores soldados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comovido com a dor que esse injusto decreto provocava, um sacerdote cat\u00f3lico chamado Valentin desafiou o imp\u00e9rio realizando, secretamente, o casamento de casais de namorados. Sua conduta o levou \u00e0 pris\u00e3o e ao mart\u00edrio e, em 14 de fevereiro de 270, ele foi executado. Ap\u00f3s in\u00fameros milagres e curas, ele foi canonizado pelo Papa Gel\u00e1sio, em 496. Desde ent\u00e3o, S\u00e3o Valentim tem sido venerado em todo o mundo como o intercessor dos namorados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim como na \u00e9poca daquele impiedoso imperador romano, a p\u00f3s-modernidade n\u00e3o parece ser uma \u00e9poca prop\u00edcia para o amor. Muito menos para o matrim\u00f4nio. Vivemos em um mundo um tanto desencantado, relativista e utilitarista. Amores duradouros parecem sucumbir a relacionamentos menos ambiciosos. H\u00e1 alguns anos, o fil\u00f3sofo polon\u00eas <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Zygmunt_Bauman\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#de7a00\" class=\"has-inline-color\">Zygmunt Bauman<\/mark><\/a> cunhou a express\u00e3o \u201camor l\u00edquido\u201d, referindo-se a uma certa tend\u00eancia \u00e0 fugacidade, ao compromisso brando e aos la\u00e7os fracos que vacilam diante do individualismo avassalador da \u00e9poca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-e-ainda-assim-o-amor-e-mais-forte\"><strong><strong>E ainda assim&#8230; o amor \u00e9 mais forte<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O encontro de duas pessoas que decidem unir seus corpos, suas almas e seus planos de vida \u00e9 uma das imagens que melhor reflete a ess\u00eancia do amor divino. A figura dos esposos \u00e9 a que o pr\u00f3prio S\u00e3o Paulo escolhe para descrever o relacionamento de Cristo com sua Igreja. Paulo proclama esse amor, que ele define como o v\u00ednculo da perfei\u00e7\u00e3o. E, embora em quest\u00f5es de casamento as receitas geralmente n\u00e3o sejam muito \u00fateis, as cartas paulinas nos fornecem um manual perfeito para os enamorados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O amor \u00e9 nutrido pela paci\u00eancia, pela generosidade, por querer o melhor para o amado. O amor n\u00e3o \u00e9 posse, embora ofere\u00e7a o dom de pertencer. O amor \u00e9, nas palavras do Padre Kentenich, estar com o outro, no outro e para o outro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A paix\u00e3o inicial \u00e9 apenas a pedra b\u00e1sica sobre a qual a intimidade de um casal \u00e9 constru\u00edda. Uma constru\u00e7\u00e3o que, muitas vezes, exige que se alargue o cora\u00e7\u00e3o e se abra a mente para entender e valorizar o mist\u00e9rio sagrado que \u00e9 o outro. Por esse motivo, al\u00e9m de sentimento, o amor exige decis\u00e3o. Amar \u00e9 um verbo, uma a\u00e7\u00e3o. Se h\u00e1 algo que n\u00e3o combina com o amor, \u00e9 a passividade de esperar que a harmonia caia do c\u00e9u, pronta para ser usada. Amar \u00e9 um exerc\u00edcio que nos envolve inteiramente. Da\u00ed a import\u00e2ncia de estarmos prontos para a magn\u00e2nima doa\u00e7\u00e3o de nosso eu pessoal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deus n\u00e3o abandona a obra de suas m\u00e3os. O milagre do amor n\u00e3o se extingue. Em meio \u00e0 crise p\u00f3s-moderna, como na Roma imperial, corpos e almas se encontram e se doam sem reservas, buscando a realiza\u00e7\u00e3o. N\u00e3o \u00e9 f\u00e1cil, por\u00e9m, o panorama para os casais de hoje, imersos em padr\u00f5es culturais que muitas vezes entram em conflito com o amor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-amor-e-matrimonio-fragilidade-e-esperanca\"><strong><strong>Amor e matrim\u00f4nio: fragilidade e esperan\u00e7a<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A verdade \u00e9 que o v\u00ednculo do amor \u00e9 t\u00e3o forte quanto delicado. Juntamente com a felicidade de compartilhar a vida com a pessoa amada, surgem dificuldades e exig\u00eancias que tornam a jornada do casal mais complexa. Esses processos vitais da vida em comum geram tens\u00f5es que podem levar, inclusive, \u00e0 separa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em sua exorta\u00e7\u00e3o apost\u00f3lica <em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/pt\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20160319_amoris-laetitia.html\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#de7a00\" class=\"has-inline-color\">Amoris laetitia<\/mark><\/a><\/em>, o Papa Francisco avalia com miseric\u00f3rdia a situa\u00e7\u00e3o daqueles que sofreram a dor da separa\u00e7\u00e3o e do div\u00f3rcio. Embora o documento deixe claro que a uni\u00e3o sacramental entre um homem livre e uma mulher livre \u00e9 o modo de vida proposto pelo Evangelho, ele tamb\u00e9m entende que esse \u00e9 um ideal que pode esbarrar na fragilidade humana. E, diante da fragilidade humana, a resposta do Evangelho \u00e9 a miseric\u00f3rdia. Nesse contexto, Francisco enfatiza como sinal de esperan\u00e7a a decis\u00e3o daqueles que, depois de experimentar o desgosto da separa\u00e7\u00e3o, tentam novamente construir uma fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talvez o div\u00f3rcio mais doloroso seja o do amor e do matrim\u00f4nio cujo hist\u00f3rico remonta h\u00e1 d\u00e9cadas. Justamente quando parecia que a humanidade havia conquistado para sempre a alegria do matrim\u00f4nio por amor. \u00c9 por medo do casamento sem amor (e de suas consequ\u00eancias devastadoras) que muitos optam por viver o amor sem o casamento. E poucos escolhem se casar na Igreja.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-color has-link-color wp-elements-f1d16fd8a67751b2d791a0b18bc60700 wp-block-paragraph\" style=\"color:#de7a00\"><em>&#8220;Para que o amor conjugal n\u00e3o seja o t\u00famulo do verdadeiro amor, os c\u00f4njuges devem ser educados no amor. Que o casamento seja uma escola de amor. Em toda escola h\u00e1 diferentes n\u00edveis de aprendizado, e o mesmo acontece na escola do amor. Deixe que o primitivismo inicial do amor m\u00fatuo se desenvolva com o tempo em um amor maduro, sereno e abnegado. A chave \u00e9 fornecer canais para que a corrente do amor divino passe por nosso amor conjugal.\u201d<\/em><\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-bbb61e65aa11dced46af5c1488a31067 wp-block-paragraph\" style=\"color:#de7a00\"><em>(Pe. Jos\u00e9 Kentenich. \u00c0s Segundas-feiras ao anoitecer. Encontros com fam\u00edlias: Amor conjugal, Caminho para a santidade. Volume 20)<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O amor de um casal \u00e9 um dom precioso de Deus e o sacramento do matrim\u00f4nio \u00e9 a maneira de faz\u00ea-lo crescer e amadurecer. Claramente, agora \u00e9 o momento para aqueles de n\u00f3s que acreditam nele darem testemunho disso com nossas vidas e proclam\u00e1-lo com alegria em nossos cora\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como S\u00e3o Valentim, n\u00f3s tamb\u00e9m podemos desafiar o imperador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonte: <\/strong><a href=\"https:\/\/www.schoenstatt.org.ar\/otros\/fiesta-de-san-valentin-del-amor-y-otros-milagros.html\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#de7a00\" class=\"has-inline-color\">schoenstatt.org.ar<\/mark><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tradu\u00e7\u00e3o: <\/strong>Karen Bueno<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape. <\/p>\n","protected":false},"author":3,"featured_media":43393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[916,876,665],"tags":[801,1059],"class_list":["post-43400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidade-pt-pt","category-familia-pt-pt","category-juventude-pt-pt","tag-familia-pt-pt","tag-matrimonio-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape - Schoenstatt<\/title>\n<meta name=\"description\" content=\"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape\" \/>\n<meta property=\"og:description\" content=\"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T02:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T18:22:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape\",\"datePublished\":\"2025-02-14T02:03:00+00:00\",\"dateModified\":\"2025-08-18T18:22:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/\"},\"wordCount\":961,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/valentines-day-love-family-1.webp\",\"keywords\":[\"Fam\u00edlia\",\"Matrim\u00f4nio\"],\"articleSection\":[\"Espiritualidade\",\"Fam\u00edlia\",\"Juventude\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/\",\"name\":\"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/valentines-day-love-family-1.webp\",\"datePublished\":\"2025-02-14T02:03:00+00:00\",\"dateModified\":\"2025-08-18T18:22:05+00:00\",\"description\":\"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/valentines-day-love-family-1.webp\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/valentines-day-love-family-1.webp\",\"width\":1280,\"height\":887},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape - Schoenstatt","description":"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/","og_locale":"pt_PT","og_type":"article","og_title":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape","og_description":"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.","og_url":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/","og_site_name":"Schoenstatt","article_published_time":"2025-02-14T02:03:00+00:00","article_modified_time":"2025-08-18T18:22:05+00:00","og_image":[{"width":1280,"height":887,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp","type":"image\/webp"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape","datePublished":"2025-02-14T02:03:00+00:00","dateModified":"2025-08-18T18:22:05+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/"},"wordCount":961,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp","keywords":["Fam\u00edlia","Matrim\u00f4nio"],"articleSection":["Espiritualidade","Fam\u00edlia","Juventude"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/","url":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/","name":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp","datePublished":"2025-02-14T02:03:00+00:00","dateModified":"2025-08-18T18:22:05+00:00","description":"Em muitos pa\u00edses, hoje \u00e9 o Dia dos Namorados. Nas cartas de Paulo, encontramos o roteiro perfeito para cultivar o amor \u00e1gape.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/02\/valentines-day-love-family-1.webp","width":1280,"height":887},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/festa-de-sao-valentim-do-amor-liquido-ao-amor-agape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"Festa de S\u00e3o Valentim: Do amor l\u00edquido ao amor \u00e1gape"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/43400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=43400"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/43400\/revisions"}],"predecessor-version":[{"id":47324,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/43400\/revisions\/47324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/43393"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=43400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=43400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=43400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}