{"id":41190,"date":"2024-09-14T03:03:00","date_gmt":"2024-09-14T01:03:00","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=41190"},"modified":"2025-05-16T00:27:35","modified_gmt":"2025-05-15T22:27:35","slug":"o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/","title":{"rendered":"O significado da Cruz da Unidade para o tempo de hoje"},"content":{"rendered":"\n<p>Como todos os anos, em 14 de setembro, juntamente com a Igreja, nossa Fam\u00edlia de Schoenstatt celebra a Exalta\u00e7\u00e3o da Santa Cruz, na v\u00e9spera de mais um anivers\u00e1rio da P\u00e1scoa de nosso Fundador, Pe. Jos\u00e9 Kentenich. Com essa festa celebramos o fato de que em 14 de setembro de 630 a rel\u00edquia da Cruz, que havia sido encontrada por Santa Helena em 320, e que fora levada da Bas\u00edlica do Santo Sepulcro pelos persas em 614, agora retorna de volta a Jerusal\u00e9m.<\/p>\n\n\n\n<p>N\u00f3s tamb\u00e9m queremos olhar para o Crucificado e descobrir na Cruz algumas das caracter\u00edsticas fundamentais da imagem de Cristo que nosso Pai e Fundador tinha.<\/p>\n\n\n\n<p>Eu n\u00e3o estava vivo na \u00e9poca em que a Cruz da Unidade foi criada. Tive o presente de ter contato com alguns dos protagonistas dessa hist\u00f3ria e quero compartilhar, com minhas pr\u00f3prias palavras, o que ouvi, juntamente com outras pessoas daquela \u00e9poca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-um-pouco-da-historia-da-cruz-da-unidade\"><strong>Um pouco da hist\u00f3ria da Cruz da Unidade<\/strong><\/h2>\n\n\n\n<p>Aproximava-se a ordena\u00e7\u00e3o dos primeiros jovens chilenos que haviam se decidido pelo sacerd\u00f3cio na comunidade dos Padres de Schoenstatt. Como sinal de gratid\u00e3o pela elei\u00e7\u00e3o e pela hist\u00f3ria que o Senhor e a M\u00e3e de Deus tinham escrito com eles, quiseram dar-lhes um presente. A princ\u00edpio, pensaram em uma coroa e, pouco a pouco, depois de uma palestra que o Pe. August Ziegler lhes deu sobre a imagem de Cristo que o Pe. Jos\u00e9 Kentenich tinha, decidiram fazer uma cruz. O primeiro chileno a ser ordenado levaria essa cruz para o Santu\u00e1rio de Bellavista.<\/p>\n\n\n\n<p>Naquela \u00e9poca, a Fam\u00edlia de Schoenstatt que vivia ao redor do Santu\u00e1rio de Bellavista estava passando por um momento de grande tens\u00e3o. O que esses jovens haviam experimentado como uma pequena antecipa\u00e7\u00e3o do para\u00edso, devido \u00e0 atmosfera familiar que se vivia, havia se rompido. Em um determinado momento, a Confer\u00eancia Episcopal Chilena chegou a proibir a entrada de novos grupos no Movimento de Schoenstatt, j\u00e1 que se tratava do per\u00edodo de ex\u00edlio do Fundador.<\/p>\n\n\n\n<p>Diante dessa situa\u00e7\u00e3o, a resposta de diferentes pessoas e comunidades foi levar a s\u00e9rio as contribui\u00e7\u00f5es para o <a href=\"https:\/\/schoenstatt.com\/pt-pt\/nossa-espiritualidade\/alianca-de-amor\/capital-de-gracas\/\">Capital de Gra\u00e7as<\/a>. \u00c9 injusto citar apenas algumas pessoas, mas h\u00e1 algumas que desempenharam um papel importante, entre outras, como Ir. M. Teofila, Mario Hiriart, Pe. Hern\u00e1n Alessandri, etc.<br>Um dos seminaristas entrou no quarto de um padre em Santa Maria, Brasil, e viu uma porcelana com a imagem de Maria ao lado da Cruz, trazida de <a href=\"https:\/\/www.maria-laach.de\/welcome-to-maria-laach-abbey.html\" target=\"_blank\" rel=\"noreferrer noopener\">Maria Laach<\/a> (local de peregrina\u00e7\u00e3o na Alemanha), e mostrou-a ao ent\u00e3o seminarista Angel Vicente, que era escultor e come\u00e7ou a trabalhar nisso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-imagem-de-cristo\"><strong>Imagem de Cristo<\/strong><\/h2>\n\n\n\n<p>Poder\u00edamos dizer que a imagem de Cristo que nosso Pai e Fundador tem \u00e9 o Cristo dos v\u00ednculos ou das vincula\u00e7\u00f5es: ela nos mostra a rela\u00e7\u00e3o de Jesus com Deus Pai, com a humanidade, com a miss\u00e3o, com Maria e consigo mesmo. Pe. August Ziegler lhes falou sobre isso quando apresentou a imagem de Cristo segundo o Pe. Jos\u00e9 Kentenich, quando lhes falou sobre o Cristo patroc\u00eantrico, fraterno, apost\u00f3lico, mariano e sacerdotal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-2-761x1024.jpg\" alt=\"\" class=\"wp-image-41187\"\/><\/figure>\n\n\n\n<p>O <strong>Cristo patroc\u00eantrico<\/strong>: \u00e9 representado pelo \u201cOlho do Pai\u201d no topo da Cruz. Ele quer expressar que Jesus s\u00f3 quer realizar a vontade do Pai, que busca ter momentos exclusivos e excludentes com Ele para conversar, discernir e fazer somente o que o Pai quer, quando Ele quer e como Ele quer.<\/p>\n\n\n\n<p>O <strong>Cristo fraterno<\/strong>: o Cristo da Cruz da Unidade n\u00e3o \u00e9 um Cristo morto, ele est\u00e1 vivo, com seus bra\u00e7os abertos para a humanidade, onde cada um de n\u00f3s tem seu espa\u00e7o. \u00c9 o Jesus para todos e cada um de n\u00f3s e que est\u00e1 em um profundo di\u00e1logo com a humanidade aos olhos de Maria.<\/p>\n\n\n\n<p>O <strong>Cristo apost\u00f3lico <\/strong>\u00e9 expresso no lado aberto, de onde fluem sangue e \u00e1gua. Essa dimens\u00e3o apost\u00f3lica \u00e9 muito mais expl\u00edcita no fundo vermelho da Cruz, onde o Sangue e o Esp\u00edrito Santo s\u00e3o, de alguma forma, o pano de fundo da entrega de Jesus. Ele foi movido pelo Esp\u00edrito para seguir a vontade do Pai e dar sua vida por cada um de n\u00f3s.<\/p>\n\n\n\n<p>O <strong>Cristo Mariano<\/strong>: essa \u00e9 possivelmente uma das caracter\u00edsticas que mais atrai nossa aten\u00e7\u00e3o. A M\u00e3e de Deus est\u00e1 ao lado do Senhor, como sempre esteve desde o primeiro momento. A presen\u00e7a de Maria na Anuncia\u00e7\u00e3o expressa que Jesus \u00e9 Deus porque sua concep\u00e7\u00e3o foi obra do Esp\u00edrito Santo. Sua presen\u00e7a na cruz expressa que Jesus \u00e9 homem, um homem que, como n\u00f3s, morre. Em seu caso, entregando-se por amor ao Pai e a n\u00f3s. \u00c9 com essa \u201ccor mariana\u201d que queremos marcar toda a nossa vida.<\/p>\n\n\n\n<p>O <strong>Cristo sacerdotal<\/strong>: n\u00e3o podemos esquecer que os jovens que estavam moldando seus desejos e os desejos do Pe. Kentenich nessa \u00e9poca eram chamados ao sacerd\u00f3cio. Eles queriam se colocar no c\u00e1lice, nas m\u00e3os da M\u00e3e de Deus, para levar ao Senhor e seu sacrif\u00edcio a todos os lugares para onde quisessem ser enviados. No C\u00e1lice da Cruz da Unidade original, h\u00e1 uma conta do ros\u00e1rio da Ir. M. Te\u00f3fila. Durante os tempos dif\u00edceis que a Fam\u00edlia de Schoenstatt estava vivendo em Bellavista, Ir. M. Te\u00f3fila disse a esses jovens que dessem tudo de si pela unidade. Esse desejo e esse pedido os marcaram n\u00e3o apenas pelo que significava e tocava seu cora\u00e7\u00e3o, mas tamb\u00e9m porque ela lhes disse que ofereceria sua vida por isso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/06\/cruz-de-la-unidad-unity-cross-2-768x1024.jpg\" alt=\"\" class=\"wp-image-37452\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-milagre-da-unidade\"><strong>O milagre da unidade<\/strong><\/h2>\n\n\n\n<p>O milagre da unidade se realizou de maneira inesperada quando o primeiro sacerdote chileno ordenado, Pe. Humberto Andwanter, celebrou a missa pela primeira vez no Santu\u00e1rio de Bellavista, a Missa dos Pastores, em 24 de dezembro de 1960. Ouvi uma das pessoas que estavam presentes naquela missa dizer que o que ele experimentou naquele momento foi como que acender uma lareira em uma sala gelada e que o calor da fam\u00edlia derreteu as barreiras que, at\u00e9 aquele momento, existiam na fam\u00edlia.<\/p>\n\n\n\n<p>Ao colocar o Cristo dos v\u00ednculos no centro da Fam\u00edlia, nossa vida \u00e9 ordenada. O amor por Deus, pelas pessoas, por si mesmo e pela miss\u00e3o \u00e9 ordenado. Nossa hist\u00f3ria \u00e9 um testemunho disso.<\/p>\n\n\n\n<p><strong>Tradu\u00e7\u00e3o:<\/strong> Karen Bueno<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.<\/p>\n","protected":false},"author":3,"featured_media":41181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[916],"tags":[],"class_list":["post-41190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidade-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O significado da Cruz da Unidade para o tempo de hoje - Schoenstatt<\/title>\n<meta name=\"description\" content=\"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O significado da Cruz da Unidade para o tempo de hoje\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-14T01:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T22:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"O significado da Cruz da Unidade para o tempo de hoje\",\"datePublished\":\"2024-09-14T01:03:00+00:00\",\"dateModified\":\"2025-05-15T22:27:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/\"},\"wordCount\":1087,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg\",\"articleSection\":[\"Espiritualidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/\",\"name\":\"O significado da Cruz da Unidade para o tempo de hoje - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg\",\"datePublished\":\"2024-09-14T01:03:00+00:00\",\"dateModified\":\"2025-05-15T22:27:35+00:00\",\"description\":\"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg\",\"width\":1600,\"height\":758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O significado da Cruz da Unidade para o tempo de hoje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O significado da Cruz da Unidade para o tempo de hoje - Schoenstatt","description":"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/","og_locale":"pt_PT","og_type":"article","og_title":"O significado da Cruz da Unidade para o tempo de hoje","og_description":"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.","og_url":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/","og_site_name":"Schoenstatt","article_published_time":"2024-09-14T01:03:00+00:00","article_modified_time":"2025-05-15T22:27:35+00:00","og_image":[{"width":1600,"height":758,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"O significado da Cruz da Unidade para o tempo de hoje","datePublished":"2024-09-14T01:03:00+00:00","dateModified":"2025-05-15T22:27:35+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/"},"wordCount":1087,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg","articleSection":["Espiritualidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/","url":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/","name":"O significado da Cruz da Unidade para o tempo de hoje - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg","datePublished":"2024-09-14T01:03:00+00:00","dateModified":"2025-05-15T22:27:35+00:00","description":"Voc\u00ea conhece o significado da Cruz da Unidade original? Sua arte inspira a vida da Fam\u00edlia de Schoenstatt no mundo todo.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2024\/09\/cruz-de-la-unidade-unity-cross-Kreuz-der-Einheit-1.jpg","width":1600,"height":758},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/o-significado-da-cruz-da-unidade-para-o-tempo-de-hoje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"O significado da Cruz da Unidade para o tempo de hoje"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/41190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=41190"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/41190\/revisions"}],"predecessor-version":[{"id":47027,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/41190\/revisions\/47027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/41181"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=41190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=41190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=41190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}