{"id":22921,"date":"2021-06-22T23:15:49","date_gmt":"2021-06-22T21:15:49","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=22921"},"modified":"2025-08-19T20:26:00","modified_gmt":"2025-08-19T18:26:00","slug":"karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/","title":{"rendered":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida"},"content":{"rendered":"<p><em>23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da <a href=\"https:\/\/schoenstatt.com\/pt-pt\/herois-de-schoenstatt\/quais-sao-as-etapas-de-um-processo-de-canonizacao\/\">beatifica\u00e7\u00e3o<\/a> de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha. Quem foi este homem, o \u00fanico di\u00e1cono que foi ordenado sacerdote em um campo de concentra\u00e7\u00e3o durante a Segunda Guerra Mundial, sob o mais estrito sigilo, e cuja for\u00e7a foi sua Alian\u00e7a de Amor com a M\u00e3e de Deus e sua paix\u00e3o por Cristo?<\/em><\/p>\n<h3 style=\"text-align: center;\">Cristo &#8211; minha paix\u00e3o<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-22909 size-full\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Karl-Leisner-im-KZ-Dez-1944.jpg\" alt=\"Cristo\" width=\"696\" height=\"889\" \/><\/p>\n<p>Em cada vida \u00e9 decisivo quem encontro, onde e em que momento. Este tamb\u00e9m \u00e9 o caso de Karl. Nascido em 28 de fevereiro de 1915, ingressou no Movimento da Juventude Cat\u00f3lica quando era estudante do ensino m\u00e9dio. L\u00e1, em 1925, ele conheceu um padre que lhe causou uma profunda impress\u00e3o: o professor de religi\u00e3o e esportes Walter Vinnenberg. Os ideais do professor e as ideias do movimento juvenil proporcionaram a Karl experi\u00eancias comunit\u00e1rias com os jovens, viv\u00eancias de longas viagens e o entusiasmo pela m\u00fasica e pelo canto. Ele encontrou uma rela\u00e7\u00e3o \u00edntima com as Sagradas Escrituras, a Missa e a Eucaristia e fez todo o poss\u00edvel para que os jovens que ele liderava se tornassem os jovens de Cristo e n\u00e3o ca\u00edssem na ideologia do Terceiro Reich. Em seu di\u00e1rio, ele escreveu: &#8220;Cristo &#8211; Voc\u00ea \u00e9 minha paix\u00e3o&#8221;. Convencido de que queria se tornar padre depois de concluir o ensino m\u00e9dio, em 1934, ele come\u00e7ou a estudar teologia em M\u00fcnster.<\/p>\n<p>O bispo de M\u00fcnster, Clemens August, percebendo rapidamente as qualidades extraordin\u00e1rias de Karl como l\u00edder juvenil, confiou ao jovem de 19 anos a posi\u00e7\u00e3o de dirigente diocesano da juventude. Isso significou que ele era respons\u00e1vel por mais de 30.000 meninos entre 10 e 14 anos, nos quais ele queria acender a paix\u00e3o por Jesus com grande alegria, \u00edmpeto e dinamismo.<\/p>\n<p>Durante o semestre, ele deixou a escola, em Friburgo, e, durante o servi\u00e7o de trabalho obrigat\u00f3rio no ver\u00e3o de 1936\/1937, ele conheceu Elisabeth, a filha da senhoria do lugar que ele alugava para morar. Nessa \u00e9poca, come\u00e7aram as duras lutas interiores: sacerd\u00f3cio ou casamento e fam\u00edlia? Na P\u00e1scoa de 1938 ele confidenciou em seu di\u00e1rio: &#8220;Senhor, eu te agrade\u00e7o por enviar esta bela e crente menina para minha vida\u201d. Por fim, ap\u00f3s muita luta, ele decidiu se tornar padre e escreveu a Elisabeth em sua carta de despedida: &#8220;Agrade\u00e7o por sua gentileza e seu amor fraterno. Eu devo muito a voc\u00ea, e Cristo me encontrou em voc\u00ea como ele nunca tinha me encontrado antes&#8221;.<\/p>\n<h3>Ordenado di\u00e1cono em 25 de mar\u00e7o de 1939, ele esperava ser ordenado sacerdote alguns meses depois. Mas, de repente ele foi diagnosticado com tuberculose grave nos pulm\u00f5es, o que o for\u00e7ou a entrar em um sanat\u00f3rio pulmonar para ser curado.<\/h3>\n<p>Foi naquele hospital que ele proferiu uma frase que lhe custaria muito caro: &#8220;Pena que ele n\u00e3o estava l\u00e1&#8221;, sobre a tentativa de assassinato de Adolf Hitler por Georg Elser em 8 de novembro de 1939. Isto levou \u00e0 sua pris\u00e3o, porque seu colega de quarto o denunciou. Ap\u00f3s v\u00e1rios per\u00edodos de deten\u00e7\u00e3o em v\u00e1rias pris\u00f5es, ele foi finalmente enviado ao campo de concentra\u00e7\u00e3o de Dachau, ao bloco dos padres, onde viviam mais de 2.700 sacerdotes de 23 na\u00e7\u00f5es, entre eles o fundador de Schoenstatt, Pe. Jos\u00e9 Kentenich.<\/p>\n<p>Em mar\u00e7o de 1942, sua doen\u00e7a pulmonar voltou a se agravar. Sabendo que ele n\u00e3o tinha muito tempo de vida, as Sagradas Escrituras e a Eucaristia, guardadas em segredo, tornaram-se um grande consolo para o jovem di\u00e1cono. De acordo com seu ideal de servir aos outros como sacerdote, ele acompanhou, espiritual e materialmente, seus companheiros prisioneiros apesar de sua doen\u00e7a, contrabandeando h\u00f3stias consagradas para os enfermos e incont\u00e1veis moribundos. Muitos contam como ele encorajou e encantou os prisioneiros com ora\u00e7\u00f5es, intercess\u00e3o e o entretenimento musical. At\u00e9 1942, ele se encontrou com um grupo secreto de Schoenstatt fundado no campo chamado &#8220;Victor in vinculis&#8221; &#8211; vencedores em cadeia &#8211; que tamb\u00e9m inclu\u00eda o Pe. Kentenich e o Pe. Joseph Fischer. Ele tinha um profundo desejo de ser ordenado sacerdote, o que parecia imposs\u00edvel, j\u00e1 que n\u00e3o havia bispo entre os prisioneiros. Mas o inesperado aconteceu: em setembro de 1944, o bispo franc\u00eas, Dom Gabriel Piguet de Clermont, chegou ao campo de concentra\u00e7\u00e3o de Dachau.<\/p>\n<p>O desejo de Karl foi apresentado a ele, e o bispo concordou em orden\u00e1-lo. Os preparativos para a celebra\u00e7\u00e3o foram feitos rapidamente e em segredo: uma carta foi enviada do acampamento ao bispo da casa de Karl pedindo permiss\u00e3o para orden\u00e1-lo, vestes episcopais e ins\u00edgnias foram feitas secretamente dos materiais mais simples, casti\u00e7ais foram feitos de latas de conserva. No domingo de Gaudete (o terceiro do Advento), em 17 de dezembro de 1944, o bispo Piguet ordenou secretamente o di\u00e1cono, gravemente doente, no bloco 26, arriscando a vida de todos os envolvidos. V\u00e1rios sacerdotes presos de todo o mundo impuseram as m\u00e3os sobre ele. Ele pr\u00f3prio s\u00f3 p\u00f4de participar desta celebra\u00e7\u00e3o com o maior esfor\u00e7o. Alguns dias depois, no Dia de Santo Est\u00eav\u00e3o, ele foi capaz de celebrar a primeira e \u00fanica Santa Missa de sua vida.<\/p>\n<p>Em 4 de maio de 1945, ele foi libertado do <a href=\"https:\/\/es.wikipedia.org\/wiki\/Campo_de_concentraci%C3%B3n_de_Dachau\">campo de concentra\u00e7\u00e3o<\/a>. Ele passou suas \u00faltimas semanas no Sanat\u00f3rio Pulmonar em Planegg, perto de Munique. Apenas dois pensamentos ainda o dominavam: amor e expia\u00e7\u00e3o. Ele morreu em 12 de agosto de 1945. Sua \u00faltima anota\u00e7\u00e3o no di\u00e1rio, em 25 de julho de 1945, dizia: &#8220;Aben\u00e7oe tamb\u00e9m, Alt\u00edssimo, meus inimigos!\u201d<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-22913 size-large\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Karl-Leisner-im-Messgewand-Dez-1944-731x1024.jpg\" alt=\"\" width=\"731\" height=\"1024\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacerdote de uma \u00fanica missa e prisioneiro dos nazistas, ele deu sua vida pela for\u00e7a de Jesus e da Alian\u00e7a de Amor<\/p>\n","protected":false},"author":3,"featured_media":22916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[888],"tags":[100,1171,1008,1097],"class_list":["post-22921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herois-de-schoenstatt-pt-pt","tag-dachau-pt-pt","tag-herois-de-schoenstatt-pt-pt","tag-padre-karl-leisner-pt-pt","tag-sacerdotes-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida - Schoenstatt<\/title>\n<meta name=\"description\" content=\"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida\" \/>\n<meta property=\"og:description\" content=\"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T21:15:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T18:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida\",\"datePublished\":\"2021-06-22T21:15:49+00:00\",\"dateModified\":\"2025-08-19T18:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/\"},\"wordCount\":970,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Familie-Leisner-Karl-unten-rechts-2.jpg\",\"keywords\":[\"Dachau\",\"Her\u00f3is de Schoenstatt\",\"Padre Karl Leisner\",\"Sacerdotes\"],\"articleSection\":[\"Her\u00f3is de Schoenstatt\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/\",\"name\":\"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Familie-Leisner-Karl-unten-rechts-2.jpg\",\"datePublished\":\"2021-06-22T21:15:49+00:00\",\"dateModified\":\"2025-08-19T18:26:00+00:00\",\"description\":\"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Familie-Leisner-Karl-unten-rechts-2.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Familie-Leisner-Karl-unten-rechts-2.jpg\",\"width\":1772,\"height\":1232,\"caption\":\"Karl Leisner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/pt-pt\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida - Schoenstatt","description":"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/","og_locale":"pt_PT","og_type":"article","og_title":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida","og_description":"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha","og_url":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/","og_site_name":"Schoenstatt","article_published_time":"2021-06-22T21:15:49+00:00","article_modified_time":"2025-08-19T18:26:00+00:00","og_image":[{"width":1772,"height":1232,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida","datePublished":"2021-06-22T21:15:49+00:00","dateModified":"2025-08-19T18:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/"},"wordCount":970,"publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg","keywords":["Dachau","Her\u00f3is de Schoenstatt","Padre Karl Leisner","Sacerdotes"],"articleSection":["Her\u00f3is de Schoenstatt"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/","url":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/","name":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg","datePublished":"2021-06-22T21:15:49+00:00","dateModified":"2025-08-19T18:26:00+00:00","description":"23 de junho \u00e9 o 25\u00ba anivers\u00e1rio da beatifica\u00e7\u00e3o de Karl Leisner pelo Papa Jo\u00e3o Paulo II em Berlim durante sua viagem \u00e0 Alemanha","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2022\/01\/Familie-Leisner-Karl-unten-rechts-2.jpg","width":1772,"height":1232,"caption":"Karl Leisner"},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/pt-pt\/karl-leisner-quando-a-paixao-e-o-amor-determinam-uma-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"Karl Leisner: quando a paix\u00e3o e o amor determinam uma vida"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/pt-pt\/#website","url":"https:\/\/schoenstatt.com\/pt-pt\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/pt-pt\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/pt-pt\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/pt-pt\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/22921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=22921"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/22921\/revisions"}],"predecessor-version":[{"id":44548,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/posts\/22921\/revisions\/44548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media\/22916"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=22921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=22921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=22921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}