{"id":69617,"date":"2026-04-10T13:56:40","date_gmt":"2026-04-10T11:56:40","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=69617"},"modified":"2026-04-15T19:05:46","modified_gmt":"2026-04-15T17:05:46","slug":"in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/","title":{"rendered":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un\u2019iniziativa nata da un\u2019esperienza personale di fede si estende oggi su pi\u00f9 continenti. Un\u2019immagine della Madonna Pellegrina \u00e8 stata inviata in Qatar e sar\u00e0 accolta da una comunit\u00e0 cattolica composta da brasiliani e da altre comunit\u00e0 di lingua portoghese. L\u2019invio ha avuto luogo il 6 aprile presso il Santuario di Schoenstatt a Londrina, nello Stato del Paran\u00e1, in Brasile. L\u2019immagine \u00e8 stata benedetta dal direttore nazionale del Movimento, p. Afonso Wosny, e l\u2019invio \u00e8 stato accompagnato dall&#8217;assistente della Campagna della Madonna Pellegrina, sr. M. Ivone Zenovello.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar-2.webp\" alt=\"\" class=\"wp-image-69538\" style=\"aspect-ratio:0.8115133455905662;width:517px;height:auto\"\/><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-una-missione-nata-dalla-vita\">Una missione nata dalla vita<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019immagine sar\u00e0 portata a Doha da Amanda Engmann Giraldes, che vive in Qatar da 11 anni. Si \u00e8 trasferita in Medio Oriente per il lavoro del marito, biologo impegnato nel campo ambientale, con particolare attenzione alle barriere coralline e alla biodiversit\u00e0 marina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fin dal suo arrivo in Qatar, Amanda ha cercato modi per vivere la fede in comunit\u00e0. <em>\u201cSono sempre stata una cattolica devota e, quando sono arrivata l\u00ec, ho cercato gruppi con cui entrare in contatto\u201d<\/em>, racconta. Da questa ricerca \u00e8 nata la partecipazione a incontri tra brasiliani e, col tempo, l\u2019avvio di attivit\u00e0 di catechesi per bambini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oggi coordina la catechesi per la comunit\u00e0 di lingua portoghese, che si riunisce nel centro religioso del Paese. Questo spazio accoglie diverse confessioni cristiane e consente di vivere la fede in un ambiente accogliente. <em>\u201cAbbiamo una comunit\u00e0 portoghese-brasiliana, con catechesi, un gruppo di donne che recita il rosario e incontri settimanali\u201d<\/em>, spiega.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d4689972.976487778!2d50.84255931302793!3d26.237193660679747!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x3e45c534ffdce87f%3A0x1cfa88cf812b4032!2sCatar!5e1!3m2!1spt-BR!2sbr!4v1775822013260!5m2!1spt-BR!2sbr\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-la-madonna-pellegrina-fa-parte-della-sua-famiglia\">La Madonna Pellegrina fa parte della sua famiglia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il legame di Amanda con l\u2019immagine della Madonna Pellegrina risale all\u2019infanzia. <em>\u201cCrescevo aspettando il giorno in cui sarebbe arrivata la Madonna Pellegrina. Pregavamo in famiglia: era un momento molto speciale\u201d<\/em>, ricorda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Determinante in questo percorso \u00e8 stata l\u2019influenza della nonna, Izaura Zuliani Sim\u00f5es. <em>\u201cHa fatto parte per molti anni del Movimento Apostolico di Schoenstatt ed \u00e8 stata per me una grande ispirazione\u201d<\/em>, afferma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il desiderio di portare l\u2019immagine in Qatar \u00e8 maturato nel tempo e si \u00e8 rafforzato alla luce della situazione attuale. <em>\u201cHo sentito nel cuore che potevo portare la Madonna Pellegrina in Qatar, soprattutto in questo tempo di guerra\u201d<\/em>, dice.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-in-tempo-di-guerra-la-madonna-pellegrina-e-segno-di-conforto\">In tempo di guerra, la Madonna Pellegrina \u00e8 segno di conforto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il Qatar si trova molto vicino all\u2019Iran e allo Stretto di Hormuz. Amanda racconta di essere rimasta a Doha negli ultimi mesi, durante il conflitto, ma recentemente \u00e8 tornata in Brasile con i figli: <em>\u201cMio marito ha ritenuto fosse meglio che partissimo, ma lui \u00e8 rimasto l\u00ec per lavoro\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secondo lei, il Qatar non \u00e8 stato colpito quanto altri Paesi della regione, pur rimanendo in stato di allerta. Descrive cos\u00ec la situazione: <em>\u201cPossiamo dire che l\u2019atmosfera \u00e8 normale, tranquilla. Il Paese \u00e8 riuscito a intercettare la maggior parte dei droni e dei missili diretti verso la citt\u00e0. Di solito riceviamo un allarme sul cellulare, molto forte e un po\u2019 spaventoso, che ci invita a metterci al riparo e a trovare un luogo sicuro, perch\u00e9 con l\u2019intercettazione dei missili possono cadere dei frammenti. Poi suona un secondo allarme, che dice che \u00e8 tutto a posto e che possiamo tornare alla vita normale. Parlando in particolare del Qatar, la vita resta tranquilla, ma sappiamo che in altri Paesi, come il Libano e Israele, \u00e8 diverso. Anche Kuwait e Bahrein, proprio qui accanto, stanno soffrendo molto\u00bb.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con l\u2019arrivo della Madonna Pellegrina, Amanda vede un nuovo segno di speranza consolante. <em>\u201cLa nostra fede \u00e8 ci\u00f2 che ci sostiene. Tra noi donne abbiamo pregato molto; abbiamo fatto anche alcuni incontri online per consolarci a vicenda. Credo che la Madonna Pellegrina, andando in visita di casa in casa, porter\u00e0 conforto e sicurezza, un senso di protezione. Credo che questa sia la grande forza che la Madre e Regina pu\u00f2 donarci, attraverso la sua intercessione presso Ges\u00f9, presso Dio, in questo momento\u201d.<\/em><\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar-3.webp\" alt=\"\" class=\"wp-image-69543\" style=\"aspect-ratio:0.7500073242902763;width:467px;height:auto\"\/><\/figure>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-accoglienza-in-qatar\">Accoglienza in Qatar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Amanda partir\u00e0 per il Qatar alla fine di questa settimana. L\u00ec, l\u2019immagine sar\u00e0 accolta dalla comunit\u00e0 cattolica di lingua portoghese. Il progetto \u00e8 che la Madonna Pellegrina visiti le famiglie, rafforzando la preghiera e la vita di fede. <em>\u201cMolte persone mi hanno gi\u00e0 detto che da bambini avevano accolto l\u2019immagine e che desiderano vivere la stessa esperienza con i propri figli\u201d<\/em>, racconta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nonostante le restrizioni agli incontri pubblici, la pratica religiosa \u00e8 consentita in ambito privato e all\u2019interno del complesso religioso. <em>\u201cPossiamo vivere la nostra fede nelle case e in quello spazio; quindi la missione sar\u00e0 possibile\u201d<\/em>, spiega.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-un-invito-a-fare-il-primo-passo\">Un invito a fare il primo passo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019obiettivo \u00e8 che la presenza della Madonna Pellegrina rafforzi i legami tra le famiglie e la comunit\u00e0. Amanda esprime anche il desiderio di approfondire la vita spirituale e, in futuro, di promuovere spazi di formazione e di preghiera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A chi sente una chiamata simile, rivolge un invito diretto:<em> \u201cMettiti in cammino, esplora le possibilit\u00e0 e prova a trasformarlo in una missione. \u00c8 questo ci\u00f2 di cui la Madonna ha bisogno: persone che vogliano portare questa grazia agli altri\u201d.<\/em><\/p>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonte:<\/strong> <a href=\"https:\/\/schoenstatt.org.br\/2026\/04\/09\/fe-brasileira-leva-mae-peregrina-ao-catar\/\" target=\"_blank\" rel=\"noreferrer noopener\">schoenstatt.org.br<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traduzione:<\/strong> Eugenio Minici<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.<\/p>\n","protected":false},"author":3,"featured_media":69532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[903],"tags":[1087,1134],"class_list":["post-69617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-madonna-pellegrina-it","tag-campagna-della-madonna-pellegrina-it","tag-schoenstatt-brasile-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente<\/title>\n<meta name=\"description\" content=\"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente\" \/>\n<meta property=\"og:description\" content=\"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T11:56:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T17:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente\",\"datePublished\":\"2026-04-10T11:56:40+00:00\",\"dateModified\":\"2026-04-15T17:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/\"},\"wordCount\":833,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pilgrim-Mother-Qatar.webp\",\"keywords\":[\"Campagna della Madonna Pellegrina\",\"Schoenstatt Brasile\"],\"articleSection\":[\"Madonna Pellegrina\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/\",\"name\":\"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pilgrim-Mother-Qatar.webp\",\"datePublished\":\"2026-04-10T11:56:40+00:00\",\"dateModified\":\"2026-04-15T17:05:46+00:00\",\"description\":\"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pilgrim-Mother-Qatar.webp\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pilgrim-Mother-Qatar.webp\",\"width\":960,\"height\":615},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/it\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente","description":"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/","og_locale":"it_IT","og_type":"article","og_title":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente","og_description":"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.","og_url":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/","og_site_name":"Schoenstatt","article_published_time":"2026-04-10T11:56:40+00:00","article_modified_time":"2026-04-15T17:05:46+00:00","og_image":[{"width":960,"height":615,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Karen Bueno","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/it\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente","datePublished":"2026-04-10T11:56:40+00:00","dateModified":"2026-04-15T17:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/"},"wordCount":833,"publisher":{"@id":"https:\/\/schoenstatt.com\/it\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp","keywords":["Campagna della Madonna Pellegrina","Schoenstatt Brasile"],"articleSection":["Madonna Pellegrina"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/","url":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/","name":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente","isPartOf":{"@id":"https:\/\/schoenstatt.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp","datePublished":"2026-04-10T11:56:40+00:00","dateModified":"2026-04-15T17:05:46+00:00","description":"In tempo di guerra, la Madonna Pellegrina giunge in un altro paese del Medio Oriente come segno di speranza e di conforto.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2026\/04\/Pilgrim-Mother-Qatar.webp","width":960,"height":615},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/it\/in-tempi-di-guerra-la-madonna-pellegrina-viene-inviata-in-qatar-nel-medio-oriente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"In tempi di guerra, la Madonna Pellegrina viene inviata in Qatar, nel Medio Oriente"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/it\/#website","url":"https:\/\/schoenstatt.com\/it\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/it\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoenstatt.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/it\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/it\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/posts\/69617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/comments?post=69617"}],"version-history":[{"count":2,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/posts\/69617\/revisions"}],"predecessor-version":[{"id":69619,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/posts\/69617\/revisions\/69619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/media\/69532"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/media?parent=69617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/categories?post=69617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/it\/wp-json\/wp\/v2\/tags?post=69617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}