{"id":33061,"date":"2023-10-16T21:26:28","date_gmt":"2023-10-16T19:26:28","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=33061"},"modified":"2025-05-15T18:25:07","modified_gmt":"2025-05-15T16:25:07","slug":"ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/","title":{"rendered":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza"},"content":{"rendered":"<h3>Viviendo el ideal de Ecuador: Familia del Padre consagrada en la patena<\/h3>\n<p>Han pasado 9 a\u00f1os desde la \u00faltima ordenaci\u00f3n sacerdotal. La <a href=\"https:\/\/schoenstatt.com\/es\/comunidades-de-schoenstatt\/joven-schoenstattiano-ecuatoriano-a-las-puertas-del-sacerdocio\/\">consagraci\u00f3n de Luis Polit<\/a> es por eso, un signo de esperanza y de renovaci\u00f3n de esta Familia, y tambi\u00e9n, un signo de la fidelidad de la Mater a su Alianza de Amor y al ideal entregado en custodia a la familia ecuatoriana: Familia del Padre consagrada en la patena.<\/p>\n<p>La patena est\u00e1 asociada al sacerdocio. Solo puede ser consagrado lo que se ofrece en la patena. Cuando hay ofrecimiento, hay magnanimidad. Cuando hay consagraci\u00f3n, hay santidad; hay amor que Dios derrama sobre aquellos que ama y elige para s\u00ed. Cuando hay consagraci\u00f3n, hay instrumentos dispuestos para el env\u00edo y la misi\u00f3n.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-33070 \" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit.jpg\" alt=\"\" width=\"1016\" height=\"572\" \/><\/p>\n<h2>Una historia de alianza<\/h2>\n<p>El P. Luis ha tenido una linda historia de amor con la Mater desde que era ni\u00f1o. Ha pertenecido pr\u00e1cticamente durante toda su vida a la Juventud Masculina. Ya a los siete a\u00f1os particip\u00f3 de los Cruzados de Schoenstatt, luego de los Pioneros, y luego de los Universitarios. Fue gestor de varios apostolados, como las misiones universitarias; fue jefe y dirigente. En toda esta trayectoria sinti\u00f3 el maternal cuidado y amor de la Virgen Mar\u00eda que lo vincul\u00f3 a su Santuario y lo fue educando en el seguimiento a su Hijo. Este profundo amor misericordioso que siempre experiment\u00f3, lo hizo sentirse predilecto de Dios, y esa predilecci\u00f3n se convirti\u00f3 en gratitud. Un coraz\u00f3n que ha experimentado ser amado, y al mismo tiempo ha amado, siempre ser\u00e1 agradecido.<\/p>\n<p>El sacerdocio del P. Luis Polit es la consecuencia de un coraz\u00f3n que vivenci\u00f3 en el Santuario y desde el Santuario la belleza de un amor grande. Su consagraci\u00f3n es simplemente una respuesta de gratitud a Dios. As\u00ed como \u00e9l ha sido amado y bendecido, as\u00ed tambi\u00e9n \u00e9l quiere amar y bendecir a todos los que Dios ponga en su camino. He aqu\u00ed el motivo para hablar de una gran esperanza.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-33066 \" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-2.jpg\" alt=\"\" width=\"998\" height=\"562\" \/><\/p>\n<h2>Cristo, alimento y sustento para todos, es su ideal<\/h2>\n<p>\u00abTomen y coman todos de \u00c9l\u00bb ha sido el lema que eligi\u00f3 para su ordenaci\u00f3n sacerdotal. La labor pastoral del neosacerdote quiere ser eso: en Cristo, alimento y sustento para todos. Es una gran alegr\u00eda poder vivir de esta manera el seguimiento a Jes\u00fas. Es una bendici\u00f3n entender la Alianza de Amor de esta manera.<\/p>\n<p>La Alianza ha impregnado toda la vida del P. Luis. Esa atm\u00f3sfera se not\u00f3 durante la celebraci\u00f3n del Sacramento del Orden que se vivi\u00f3 en la Catedral. En un ambiente de familia y de profunda alegr\u00eda y de densidad espiritual, todos fuimos abrazados por Dios, sostenidos en su amor.<\/p>\n<p>En tiempos dif\u00edciles para la Iglesia y la sociedad <a href=\"https:\/\/www.schoenstatt.ec\/\" target=\"_blank\" rel=\"noopener\">ecuatoriana<\/a>, nos hace bien cultivar el sentido de alianza, nos hace bien sentir el b\u00e1lsamo de la misericordia de Dios, nos hace bien tener certeza de su presencia.<\/p>\n<h3><img decoding=\"async\" class=\"aligncenter wp-image-33078 \" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-5.jpg\" alt=\"\" width=\"1014\" height=\"571\" \/><\/h3>\n<h3>Agradecimiento y ofrenda<\/h3>\n<p>Gracias a todos los que en el camino de vida del P. Luis han sido sembradores de la Alianza y del Evangelio en su coraz\u00f3n, especialmente su madre, Mirella de Polit, integrante del c\u00edrculo de Si\u00f3n, que reza por vocaciones y por los Padres de Schoenstatt, y tambi\u00e9n es parte de la Liga de Madres. Su ejemplo, junto con el de su padre, don Ricardo Polit, ya en el cielo, fueron determinantes para el aprendizaje a descubrir el llamado de Dios.<\/p>\n<p>A nosotros solo nos queda agradecer, y como el P. Luis, tambi\u00e9n ser fieles al llamado, a ofrecerle todo y consagrarnos al servicio del amor y de la vida; es lo que se espera de un hijo de la Familia del Padre consagrada en la Patena.\u00a1Fidelidad por Fidelidad!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-33074 \" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-4.jpg\" alt=\"\" width=\"1041\" height=\"586\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado 14 de octubre hemos sido testigos de una gran bendici\u00f3n para la Familia de Schoenstatt ecuatoriana. Luis Polit Estrella, ecuatoriano, miembro del Instituto de los Padres de Schoenstatt, ha sido ordenado sacerdote de Cristo en la Catedral de Guayaquil, Ecuador.<\/p>\n","protected":false},"author":3,"featured_media":33062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909,790],"tags":[],"class_list":["post-33061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-de-schoenstatt-es","category-paises-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza<\/title>\n<meta name=\"description\" content=\"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza\" \/>\n<meta property=\"og:description\" content=\"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-16T19:26:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T16:25:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza\",\"datePublished\":\"2023-10-16T19:26:28+00:00\",\"dateModified\":\"2025-05-15T16:25:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/\"},\"wordCount\":653,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ordenacion-luiz-polit-3-1.jpg\",\"articleSection\":[\"Comunidades de Schoenstatt\",\"Pa\u00edses\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/\",\"name\":\"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ordenacion-luiz-polit-3-1.jpg\",\"datePublished\":\"2023-10-16T19:26:28+00:00\",\"dateModified\":\"2025-05-15T16:25:07+00:00\",\"description\":\"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ordenacion-luiz-polit-3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ordenacion-luiz-polit-3-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza","description":"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/","og_locale":"es_ES","og_type":"article","og_title":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza","og_description":"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.","og_url":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/","og_site_name":"Schoenstatt","article_published_time":"2023-10-16T19:26:28+00:00","article_modified_time":"2025-05-15T16:25:07+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza","datePublished":"2023-10-16T19:26:28+00:00","dateModified":"2025-05-15T16:25:07+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/"},"wordCount":653,"publisher":{"@id":"https:\/\/schoenstatt.com\/es\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg","articleSection":["Comunidades de Schoenstatt","Pa\u00edses"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/","url":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/","name":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza","isPartOf":{"@id":"https:\/\/schoenstatt.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg","datePublished":"2023-10-16T19:26:28+00:00","dateModified":"2025-05-15T16:25:07+00:00","description":"El ecuatoriano Luis Polit, miembro del Instituto de los Padres de Schoenstatt, fue ordenado sacerdote en la Catedral de Guayaquil.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ordenacion-luiz-polit-3-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/es\/ecuador-de-fiesta-por-su-neosacerdote-el-p-luis-polit-una-vida-de-alianza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Ecuador de fiesta por su neosacerdote: El P. Luis Polit, una vida de Alianza"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/es\/#website","url":"https:\/\/schoenstatt.com\/es\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/es\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/es\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/33061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/comments?post=33061"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/33061\/revisions"}],"predecessor-version":[{"id":46373,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/33061\/revisions\/46373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/media\/33062"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/media?parent=33061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/categories?post=33061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/tags?post=33061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}