{"id":32860,"date":"2023-10-12T06:00:15","date_gmt":"2023-10-12T04:00:15","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=32860"},"modified":"2025-05-15T18:38:27","modified_gmt":"2025-05-15T16:38:27","slug":"novena-18-de-octubre-dia-4","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/","title":{"rendered":"NOVENA &#8211; 18 de octubre &#8211; D\u00eda 4"},"content":{"rendered":"<p>\u00danete a nosotros en la novena para el D\u00eda de <a href=\"https:\/\/schoenstatt.com\/es\/acerca-de\/espiritualidad\/alianza-de-amor\/\">Alianza de Amor<\/a> en el Santuario Original. La novena tiene lugar del 9 al 17 de octubre, siempre a las 19:50 (hora alemana).<\/p>\n<p>El cuarto d\u00eda, nuestra mirada se dirige a la imagen de la Virgen, y tambi\u00e9n a su corona. Nuestro tiempo est\u00e1 marcado por la cultura de la comparaci\u00f3n, la desvalorizaci\u00f3n y la discriminaci\u00f3n. En el Santuario, la MTA nos ayuda a redescubrir nuestro valor y dignidad.<\/p>\n<h2>Reza desde casa<\/h2>\n<p>La novena se retransmite cada d\u00eda en directo a trav\u00e9s de la webcam del Santuario Original. Se rezar\u00e1 durante la bendici\u00f3n vespertina, siempre a las 19h50 (hora alemana).<\/p>\n<p>Si no puedes conectarte a las retransmisiones, no hay problema. Te invitamos a rezar la novena en familia o con tu grupo del Movimiento.<\/p>\n<p><strong>Para participar, descarga el contenido:&nbsp;<\/strong><\/p>\n<p><a class=\"fasc-button fasc-size-medium fasc-type-flat fasc-style-bold\" style=\"background-color: #10217d; color: #ffffff;\" target=\"_blank\" href=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/ES-Dia-4.pdf\" rel=\"noopener\">Novena en espa\u00f1ol<\/a><\/p>\n<p>Para ver las retransmisiones &#8211; accede a la <strong>webcam: <a href=\"https:\/\/urheiligtum.de\/PT\/10-Servico\/99-Webcam.php\" target=\"_blank\" rel=\"noopener\">haz clic aqu\u00ed<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sigue la novena para el D\u00eda de Alianza. Hoy, 12 de octubre, es el cuarto d\u00eda. Descarga el material y podr\u00e1s rezar desde casa. <\/p>\n","protected":false},"author":3,"featured_media":32846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[630,901],"tags":[],"class_list":["post-32860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-es","category-santuario-original-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NOVENA - 18 de octubre - D\u00eda 4 - Schoenstatt<\/title>\n<meta name=\"description\" content=\"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOVENA - 18 de octubre - D\u00eda 4\" \/>\n<meta property=\"og:description\" content=\"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-12T04:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T16:38:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1358\" \/>\n\t<meta property=\"og:image:height\" content=\"1053\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"NOVENA &#8211; 18 de octubre &#8211; D\u00eda 4\",\"datePublished\":\"2023-10-12T04:00:15+00:00\",\"dateModified\":\"2025-05-15T16:38:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MTA-mae-mater-novena-1.jpg\",\"articleSection\":[\"Eventos\",\"Santuario Original\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/\",\"name\":\"NOVENA - 18 de octubre - D\u00eda 4 - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MTA-mae-mater-novena-1.jpg\",\"datePublished\":\"2023-10-12T04:00:15+00:00\",\"dateModified\":\"2025-05-15T16:38:27+00:00\",\"description\":\"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MTA-mae-mater-novena-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MTA-mae-mater-novena-1.jpg\",\"width\":1358,\"height\":1053},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/novena-18-de-octubre-dia-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOVENA &#8211; 18 de octubre &#8211; D\u00eda 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/es\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NOVENA - 18 de octubre - D\u00eda 4 - Schoenstatt","description":"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/","og_locale":"es_ES","og_type":"article","og_title":"NOVENA - 18 de octubre - D\u00eda 4","og_description":"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!","og_url":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/","og_site_name":"Schoenstatt","article_published_time":"2023-10-12T04:00:15+00:00","article_modified_time":"2025-05-15T16:38:27+00:00","og_image":[{"width":1358,"height":1053,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karen Bueno","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"NOVENA &#8211; 18 de octubre &#8211; D\u00eda 4","datePublished":"2023-10-12T04:00:15+00:00","dateModified":"2025-05-15T16:38:27+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/"},"wordCount":169,"publisher":{"@id":"https:\/\/schoenstatt.com\/es\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg","articleSection":["Eventos","Santuario Original"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/","url":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/","name":"NOVENA - 18 de octubre - D\u00eda 4 - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg","datePublished":"2023-10-12T04:00:15+00:00","dateModified":"2025-05-15T16:38:27+00:00","description":"Hoy, 12 de octubre, estamos en el cuarto d\u00eda de la novena. \u00a1S\u00edguela en directo v\u00eda webcam desde el Santuario Original!","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/10\/MTA-mae-mater-novena-1.jpg","width":1358,"height":1053},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/es\/novena-18-de-octubre-dia-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"NOVENA &#8211; 18 de octubre &#8211; D\u00eda 4"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/es\/#website","url":"https:\/\/schoenstatt.com\/es\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/es\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/es\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/es\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/32860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/comments?post=32860"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/32860\/revisions"}],"predecessor-version":[{"id":46335,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/posts\/32860\/revisions\/46335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/media\/32846"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/media?parent=32860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/categories?post=32860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/es\/wp-json\/wp\/v2\/tags?post=32860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}