{"id":63441,"date":"2025-09-05T13:41:32","date_gmt":"2025-09-05T11:41:32","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=63441"},"modified":"2025-09-05T16:05:54","modified_gmt":"2025-09-05T14:05:54","slug":"die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/","title":{"rendered":"Die Koffer sind gepackt&#8230; Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!"},"content":{"rendered":"\n<p>Missionare und Verantwortliche aus verschiedenen Ecken der Welt reisen an, um daran teilzunehmen. In den n\u00e4chsten Tagen werden 700 Vertreter aus 25 L\u00e4ndern in Santa Maria im S\u00fcden Brasiliens zusammenkommen.<\/p>\n\n\n\n<p>Das vom 10. bis 14. September stattfindende Treffen bietet Momente der Bildung, der Spiritualit\u00e4t, der Diskussion und des internationalen Austausches an dem Ort, an dem die <a href=\"https:\/\/schoenstatt.com\/de\/in-mission\/kirche\/kampagne-der-pilgernden-gottesmutter\/\">Kampagne<\/a> begonnen hat.<\/p>\n\n\n\n<p>Es werden Vertreter aus folgenden L\u00e4ndern teilnehmen: Deutschland, Spanien, Portugal, Polen, Kroatien, die Slowakei, Italien, Luxemburg, die Vereinigten Staaten, Mexiko, Guatemala, Peru, Bolivien, Kolumbien, Chile, Ecuador, Argentinien, Paraguay, Uruguay, Brasilien, Puerto Rico, die Dominikanische Republik, Burundi, Indien und die Philippinen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kroatien-wir-hatten-nie-gedacht-dass-wir-teilnehmen-wurden\">Kroatien: \u201eWir h\u00e4tten nie gedacht, dass wir teilnehmen w\u00fcrden\u201c<\/h3>\n\n\n\n<p>Anita und Dino Crnjak, die ihr Land vertreten werden, sehen diesen Kongress als eine ganz besondere Gelegenheit.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote has-medium-font-size\" style=\"border-top-color:var(--wp--preset--color--luminous-vivid-orange);border-top-style:solid;border-top-width:1px;border-bottom-color:var(--wp--preset--color--luminous-vivid-orange);border-bottom-style:solid;border-bottom-width:1px;font-style:italic;font-weight:300\"><blockquote><p>\u201eBis vor kurzem war Brasilien f\u00fcr uns als Familie eine unvorstellbare und unm\u00f6gliche Reise. Wir gehen als Apostel der K\u00f6nigin der Zukunft, und wir wissen, dass f\u00fcr die Gottesmutter nichts unm\u00f6glich ist. Wir sind sehr stolz, an diesem gro\u00dfen Jubil\u00e4um teilzunehmen \u2013 sowohl pers\u00f6nlich als auch als Familie und als Vertreter der kroatischen Sch\u00f6nstattfamilie. Wir haben Vertrauen und glauben fest daran, dass die MTA mit ihren Aposteln durch dieses Jubil\u00e4um die Welt und die Kirche erobern wird.<br>Die Welt braucht die MTA! Sie ist eine Missionarin, die Wunder wirken wird. Ihr Wunder ist, dass wir an der Quelle sein k\u00f6nnen, an der Jo\u00e3o Luiz Pozzobon als Apostel und Missionar zu dienen begann.\u201c<\/p><cite>Anita und Dino Crnjak<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-in-der-slowakei-ist-ihr-bild-klein-aber-sie-selbst-ist-gross\">In der Slowakei ist ihr Bild klein, aber sie selbst ist gro\u00df<\/h3>\n\n\n\n<p>M\u00e1ria P\u00fa\u010dkov\u00e1, die Vertreterin der Slowakei, erkl\u00e4rt, warum sie beim Kongress anwesend sein wollte:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/family-of-Slovakia-pilgrim-mother.jpg\" alt=\"\" class=\"wp-image-63423\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/family-of-Slovakia-pilgrim-mother.jpg 1600w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/family-of-Slovakia-pilgrim-mother-768x576.jpg 768w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/family-of-Slovakia-pilgrim-mother-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-pullquote has-medium-font-size\" style=\"border-top-color:var(--wp--preset--color--luminous-vivid-orange);border-top-style:solid;border-top-width:1px;border-bottom-color:var(--wp--preset--color--luminous-vivid-orange);border-bottom-style:solid;border-bottom-width:1px;font-style:italic;font-weight:300\"><blockquote><p>\u201eDie Gottesmutter, unsere liebe MTA, wirkt Wunder in meinem Dorf und in meinem Land. Ihr Bild ist klein, aber sie ist gro\u00df: Sie handelt, sie heilt und hilft uns jeden Tag. Ich m\u00f6chte die Gnaden dieses Kongresses sammeln, um sie mit anderen zu teilen und um zu danken. Wir vertrauen auf sie und auf ihren Sohn, den guten Gott, unseren Vater.\u201c<\/p><cite>M\u00e1ria P\u00fa\u010dkov\u00e1<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-spanien-erfahrungsaustausch-mit-anderen-landern\">Spanien: Erfahrungsaustausch mit anderen L\u00e4ndern<\/h3>\n\n\n\n<p>Eulalia Sol\u00e9 aus Spanien schildert ihre Erwartungen an die Tage des Treffens:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote has-medium-font-size\" style=\"border-top-color:var(--wp--preset--color--luminous-vivid-orange);border-top-style:solid;border-top-width:1px;border-bottom-color:var(--wp--preset--color--luminous-vivid-orange);border-bottom-style:solid;border-bottom-width:1px;font-style:italic;font-weight:300\"><blockquote><p>\u201eZun\u00e4chst einmal m\u00f6chte ich sagen, dass ich mich sehr freue und dankbar bin, an diesem Treffen teilnehmen zu k\u00f6nnen. Ich hoffe, dass wir durch den Erfahrungsaustausch mit Menschen aus anderen L\u00e4ndern, die aktiv an der Kampagne der Pilgernden Gottesmutter teilnehmen, durch das Kennenlernen der Orte, an denen das Apostolat begann, und durch das Kennenlernen von Jo\u00e3o Pozzobon, dem ersten Missionar, alle bereichert abreisen k\u00f6nnen, um die Entwicklung in unseren verschiedenen L\u00e4ndern mit neuer Kraft fortzusetzen.<br>Ich hoffe auch, dass wir alle die Gnaden dieses Jubil\u00e4ums als eine neue Aussendung vom Taborheiligtum aus empfangen, damit die Pilgernde Gottesmutter die ganze Welt bereisen kann und immer mehr Menschen ihr und Jesus begegnen k\u00f6nnen. M\u00f6ge es als gro\u00dfer Impuls f\u00fcr alle dienen!\u201c<\/p><cite>Eulalia Sol\u00e9<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-dominikanische-republik-die-kampagne-ist-in-den-letzten-jahren-gewachsen\">Dominikanische Republik: Die Kampagne ist in den letzten Jahren gewachsen<\/h3>\n\n\n\n<p>Pedro Abreu aus der Dominikanischen Republik erz\u00e4hlt uns, wie sich die Kampagne in den verschiedenen Regionen des Landes ausgebreitet hat und welche Erwartungen er an den Kongress hat.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:41% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"863\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/missionary-from-the-Dominican-Republic-pilgrim-mother.jpg\" alt=\"\" class=\"wp-image-63428 size-full\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/missionary-from-the-Dominican-Republic-pilgrim-mother.jpg 800w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/missionary-from-the-Dominican-Republic-pilgrim-mother-768x828.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>\u201eIch geh\u00f6re zu einer Delegation von 22 Pilgern der Hoffnung aus der Dominikanischen Republik. Derzeit haben wir etwa 4.000 Bilder der Pilgernden Gottesmutter in der n\u00f6rdlichen Region und weitere 3.000 in der Stadt Santo Domingo. Anl\u00e4sslich des 50-j\u00e4hrigen Jubil\u00e4ums der Kampagne haben wir ein Auxiliar-Bild erhalten, das wir in der s\u00fcdlichen Region einsetzen werden. Nach diesem Kongress werden wir ein weiteres Auxiliar-Bild anl\u00e4sslich des 75-j\u00e4hrigen Jubil\u00e4ums erhalten, das in der n\u00f6rdlichen Region des Landes eingesetzt werden wird.<br>Wir erwarten, dass wir anl\u00e4sslich dieses Jubil\u00e4ums die Erfahrungen und Zeugnisse anderer Pilger der Hoffnung aus anderen L\u00e4ndern teilen und h\u00f6ren k\u00f6nnen. Zudem m\u00f6chten wir uns ein Bild von unserer zuk\u00fcnftigen Arbeit als Missionare der Pilgernden Gottesmutter machen.\u201c<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Pedro Abreu<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background\" style=\"background-color:#f87213;color:#f87213\"\/>\n<\/div><\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\u00dcbersetzung: <\/strong>Vanessa Franke<br><strong>Lektorat:<\/strong> Hildegard Kaiser<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.<\/p>\n","protected":false},"author":3,"featured_media":63436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[902],"tags":[1086,1133],"class_list":["post-63441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pilgerheiligtum-de","tag-apostolat-der-pilgernden-gottesmutter-de","tag-schonstatt-brasilien-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!<\/title>\n<meta name=\"description\" content=\"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!\" \/>\n<meta property=\"og:description\" content=\"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T11:41:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T14:05:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Die Koffer sind gepackt&#8230; Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!\",\"datePublished\":\"2025-09-05T11:41:32+00:00\",\"dateModified\":\"2025-09-05T14:05:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/\"},\"wordCount\":693,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp\",\"keywords\":[\"Apostolat der Pilgernden Gottesmutter\",\"Sch\u00f6nstatt Brasilien\"],\"articleSection\":[\"Pilgerheiligtum\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/\",\"name\":\"Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp\",\"datePublished\":\"2025-09-05T11:41:32+00:00\",\"dateModified\":\"2025-09-05T14:05:54+00:00\",\"description\":\"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp\",\"width\":2048,\"height\":1360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Koffer sind gepackt&#8230; Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!","description":"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/","og_locale":"de_DE","og_type":"article","og_title":"Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!","og_description":"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.","og_url":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/","og_site_name":"Schoenstatt","article_published_time":"2025-09-05T11:41:32+00:00","article_modified_time":"2025-09-05T14:05:54+00:00","og_image":[{"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp","width":2048,"height":1360,"type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Karen Bueno","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Die Koffer sind gepackt&#8230; Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!","datePublished":"2025-09-05T11:41:32+00:00","dateModified":"2025-09-05T14:05:54+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/"},"wordCount":693,"publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp","keywords":["Apostolat der Pilgernden Gottesmutter","Sch\u00f6nstatt Brasilien"],"articleSection":["Pilgerheiligtum"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/","url":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/","name":"Die Koffer sind gepackt... Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp","datePublished":"2025-09-05T11:41:32+00:00","dateModified":"2025-09-05T14:05:54+00:00","description":"In wenigen Tagen werden sich 700 Vertreter der Kampagne aus 25 L\u00e4ndern zu einem internationalen Kongress in Brasilien versammeln.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/09\/Santa-Maria-Shrine-Brazil-Pilgrim-Mother.webp","width":2048,"height":1360},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/de\/die-koffer-sind-gepackt-die-vorfreude-auf-den-kongress-der-kampagne-der-pilgernden-gottesmutter-ist-gross\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Die Koffer sind gepackt&#8230; Die Vorfreude auf den Kongress der Kampagne der Pilgernden Gottesmutter ist gro\u00df!"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/de\/#website","url":"https:\/\/schoenstatt.com\/de\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/de\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/de\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/63441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/comments?post=63441"}],"version-history":[{"count":5,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/63441\/revisions"}],"predecessor-version":[{"id":63477,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/63441\/revisions\/63477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media\/63436"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media?parent=63441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/categories?post=63441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/tags?post=63441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}