{"id":49130,"date":"2023-07-21T12:38:53","date_gmt":"2023-07-21T10:38:53","guid":{"rendered":"https:\/\/schoenstattdev.wpenginepowered.com\/spiritualitat\/three-schoenstatters-called-to-the-synod-let-us-pray-for-them\/"},"modified":"2025-05-15T19:33:39","modified_gmt":"2025-05-15T17:33:39","slug":"drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/","title":{"rendered":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!"},"content":{"rendered":"<p>Der Vatikan hat letzte Woche die <a href=\"https:\/\/www.synod.va\/en\/news\/list-of-the-participants-to-the-xvi-general-ordinary-assembly-of.html\" target=\"_blank\" rel=\"noopener\">Namensliste<\/a> f\u00fcr die n\u00e4chste <strong>Generalversammlung der Synode<\/strong> vorgestellt, die im Oktober 2023 in Rom stattfinden wird. Unter den mehr als 360 Berufenen sind auch drei <a href=\"https:\/\/schoenstattdev.wpenginepowered.com\/de\/familie\/gemeinschaften-in-der-schoenstattbewegung\/\">Mitglieder der Apostolischen Sch\u00f6nstattbewegung<\/a>.<\/p>\n<p>Als Familie sind wir eingeladen, zu beten und den Heiligen Geist f\u00fcr jeden von ihnen und f\u00fcr diesen wichtigen Moment im Leben der Kirche zu erbitten. Sie sind:<\/p>\n<h2>Monsignore Ram\u00f3n Alfredo de la Cruz Baldera aus der Dominikanischen Republik<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-31472 \" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/monsenor-ramon-alfredo-de-la-cruz-baldera-1.png\" alt=\"\" width=\"738\" height=\"630\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/monsenor-ramon-alfredo-de-la-cruz-baldera-1.png 840w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/monsenor-ramon-alfredo-de-la-cruz-baldera-1-768x656.png 768w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/p>\n<p>Monsignore Ram\u00f3n Alfredo de la Cruz Baldera ist Mitglied des <strong>Sch\u00f6nstatt-Instituts der Di\u00f6zesanpriester<\/strong>. Er ist Bischof der Di\u00f6zese von San Francisco de Macoris in der Dominikanischen Republik.<\/p>\n<p>In einem Brief an die Priester der Di\u00f6zese schreibt er: <em>&#8222;Die Sendung, das Reich Gottes zu bauen, l\u00e4dt uns zu einer st\u00e4ndigen Erneuerung der Kirche ein. Heute hat dies einen Namen: die Kirche der Synodalit\u00e4t. Die Synodalit\u00e4t stellt uns vor viele Herausforderungen, Herausforderungen, von denen wir manchmal nicht wissen, ob wir sie bew\u00e4ltigen k\u00f6nnen, aber andererseits sind wir zuversichtlich, dass der Herr dem Boot des Petrus einen guten Steuermann gegeben hat, der es zusammen mit vielen Bisch\u00f6fen, Priestern, Ordensleuten und Laien in einen guten Hafen bringen wird.&#8220;<\/em><\/p>\n<h2>Monsignore Nicolas Nadji Bab, Bischof von Tschad<\/h2>\n<h2><img decoding=\"async\" class=\"wp-image-31476\" style=\"font-size: 14px;\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/Dom-Nicolas-Nadji-Bab-1.jpg\" alt=\"\" width=\"850\" height=\"425\" srcset=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/Dom-Nicolas-Nadji-Bab-1.jpg 1360w, https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/Dom-Nicolas-Nadji-Bab-1-768x384.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/h2>\n<p>Msgr. Nicolas Nadji Bab war 2019 zur Hundertjahrfeier von H\u00f6rde in Sch\u00f6nstattNicolas Nadji Bab, geh\u00f6rt zum <strong>Sch\u00f6nstatt-Di\u00f6zesanpriesterbund<\/strong>. Als Bischof ist er zust\u00e4ndig f\u00fcr die Di\u00f6zese La\u00ef im afrikanischen Land Tschad.<\/p>\n<p>Nicolas Bab lernte die Sch\u00f6nstattbewegung durch den Schweizer Pater Alois Baumberger kennen, der viele Jahre in der Di\u00f6zese Pala im S\u00fcden des Tschad t\u00e4tig war.<\/p>\n<p>Seine Kursbr\u00fcder sind Priester in den Di\u00f6zesen Pala, Moundou, Sarh und La\u00ef. Sie waren 2019 in Sch\u00f6nstatt bei der Feier \u201e100 Jahre Apostolischer Bund Sch\u00f6nstatt: H\u00f6rde 1919\u201c.<\/p>\n<h2>Pedro Paulo Weizenmann, aus Brasilien<\/h2>\n<figure id=\"attachment_31480\" aria-describedby=\"caption-attachment-31480\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-31480 size-full\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/familias-weinzenman-schoenstatt-1.png\" alt=\"\" width=\"720\" height=\"540\" \/><figcaption id=\"caption-attachment-31480\" class=\"wp-caption-text\">Pedro Paulo mit seinen Eltern in Sch\u00f6nstatt<\/figcaption><\/figure>\n<p>Unter den Laien, die an der Versammlung teilnehmen werden, ist der junge Pedro Paulo Weizenmann. Er wird als Freiwilliger im Synodensekretariat arbeiten, wo er bereits seit einiger Zeit t\u00e4tig ist. Pedro Paulo war viele Jahre lang Mitglied der <strong>Sch\u00f6nstatt-Mannesjugend<\/strong> vom Heiligtum in Vila Mariana, S\u00e3o Paulo, Brasilien. Mit einer Familie, die seit vielen Jahren zur Sch\u00f6nstattbewegung geh\u00f6rt, nimmt er aktiv an Misiones, Foren und Gruppen der Bewegung in seiner Di\u00f6zese teil.<\/p>\n<p>Pedro Paulo nahm das erste Bild der Pilgernden Gottesmutter mit an die Harvard University in den Vereinigten Staaten, wo er studierte. Er nahm die MTA auch mit zu seinem Praktikum bei der UNO im Jahr 2019.<\/p>\n<h3>Lasst uns f\u00fcr alle Synodenteilnehmer beten<\/h3>\n<p>Insgesamt werden 363 stimmberechtigte Mitglieder an der Vollversammlung teilnehmen. Darunter sind 85 Frauen, von denen 54 stimmberechtigt sind. Begleiten wir sie alle mit unserem Gebet und Opfer und legen alles ins <a href=\"https:\/\/schoenstattdev.wpenginepowered.com\/de\/about\/spiritualitaet\/gnadenkapital\/\">Gnadenkapital<\/a>, damit die Synode eine Pfingstzeit im Leben der Weltkirche sein m\u00f6ge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Vatikan hat die Liste der Teilnehmer an der Generalversammlung der Synode ver\u00f6ffentlicht. Darunter sind auch drei Mitglieder der Sch\u00f6nstattbewegung: zwei Bisch\u00f6fe und ein Laie.<\/p>\n","protected":false},"author":3,"featured_media":31488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[851],"tags":[],"class_list":["post-49130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kirche-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!<\/title>\n<meta name=\"description\" content=\"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!\" \/>\n<meta property=\"og:description\" content=\"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T10:38:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T17:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1332\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!\",\"datePublished\":\"2023-07-21T10:38:53+00:00\",\"dateModified\":\"2025-05-15T17:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/\"},\"wordCount\":499,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/convocados-para-o-sinodo-1.jpg\",\"articleSection\":[\"Kirche\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/\",\"name\":\"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/convocados-para-o-sinodo-1.jpg\",\"datePublished\":\"2023-07-21T10:38:53+00:00\",\"dateModified\":\"2025-05-15T17:33:39+00:00\",\"description\":\"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/convocados-para-o-sinodo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/convocados-para-o-sinodo-1.jpg\",\"width\":1332,\"height\":680,\"caption\":\"Tres schoenstattianos llamados al S\u00ednodo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!","description":"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/","og_locale":"de_DE","og_type":"article","og_title":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!","og_description":"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie","og_url":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/","og_site_name":"Schoenstatt","article_published_time":"2023-07-21T10:38:53+00:00","article_modified_time":"2025-05-15T17:33:39+00:00","og_image":[{"width":1332,"height":680,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Karen Bueno","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!","datePublished":"2023-07-21T10:38:53+00:00","dateModified":"2025-05-15T17:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/"},"wordCount":499,"publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg","articleSection":["Kirche"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/","url":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/","name":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg","datePublished":"2023-07-21T10:38:53+00:00","dateModified":"2025-05-15T17:33:39+00:00","description":"Die Liste der zur Synode geladenen Teilnehmer wurde bekannt gegeben. Unter ihnen befinden sich drei Sch\u00f6nst\u00e4tter: zwei Bisch\u00f6fe und ein Laie","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2023\/07\/convocados-para-o-sinodo-1.jpg","width":1332,"height":680,"caption":"Tres schoenstattianos llamados al S\u00ednodo"},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/de\/drei-schoenstaetter-zur-synode-berufen-lasst-uns-fuer-sie-beten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Drei Sch\u00f6nst\u00e4tter zur Synode berufen: Lasst uns f\u00fcr sie beten!"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/de\/#website","url":"https:\/\/schoenstatt.com\/de\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/de\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/de\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/49130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/comments?post=49130"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/49130\/revisions"}],"predecessor-version":[{"id":49236,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/49130\/revisions\/49236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media\/31488"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media?parent=49130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/categories?post=49130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/tags?post=49130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}