{"id":18987,"date":"2021-09-21T21:31:46","date_gmt":"2021-09-21T19:31:46","guid":{"rendered":"https:\/\/schoenstatt.com\/?p=18987"},"modified":"2025-08-18T17:47:27","modified_gmt":"2025-08-18T15:47:27","slug":"unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas","status":"publish","type":"post","link":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/","title":{"rendered":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas"},"content":{"rendered":"<h3>Fr\u00fcchte des Einf\u00fchrungskurses in Sch\u00f6nstatt &#8211; CIS &#8211; in Mittelamerika<\/h3>\n<p>In Mittelamerika wurde der Einf\u00fchrungskurs in Sch\u00f6nstatt (CIS) im Jahr 2020 virtuell abgehalten und verzeichnete eine gro\u00dfe Anzahl von Ehepaaren, die inmitten der physischen Isolation eine spirituelle Verbindung mit Menschen mit den gleichen Werten und Idealen suchten. Die Gruppe wurde durch eine gro\u00dfe Anzahl von Paaren aus verschiedenen lateinamerikanischen L\u00e4ndern, darunter auch Venezuela, bereichert.<\/p>\n<p>Das Ehepaar Janeth Gonz\u00e1lez und Antonio Noda, die zur <a href=\"https:\/\/www.instagram.com\/schoenstatt.venezuela\/?hl=de\" target=\"_blank\" rel=\"noopener\">Sch\u00f6nstatt-Bewegung<\/a> geh\u00f6ren wollten, waren von Venezuela aus bei allen Treffen aktiv und zeigten eine gro\u00dfe Liebe zur Gottesmutter und vor allem eine apostolische Kraft, die in jedem Beitrag sp\u00fcrbar war.<\/p>\n<p>Sch\u00f6nstatt ist seit den 1980er-Jahren in Venezuela pr\u00e4sent, besonders mit der Teilnahme an der Kampagne der Pilgernden Gottesmutter, dem Beten des Rosenkranzes f\u00fcr eine Million Kinder und dem Bau von mindestens zwei Bildst\u00f6cken in Caracas. Die Bewegung war nicht in Form von Gruppen oder Zweigstellen organisiert und blieb in anderen venezolanischen St\u00e4dten wie Valencia, Barquisimeto und Chichiriviche verstreut.<\/p>\n<p>Mit Unterst\u00fctzung des CIS vertiefte das Ehepaar Noda Gonz\u00e1lez seine Selbstbildung mit einem venezolanischen Ehepaar, das den Sch\u00f6nstatt-Ehepaaren angeh\u00f6rt und das sie von Costa Rica aus unterst\u00fctzte. Ihnen wurden Schulungsb\u00fccher und andere Materialien geschickt, damit sie die Aufgabe \u00fcbernehmen konnten, der Bewegung in Caracas neues Leben einzuhauchen.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-18973 size-full\" src=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.10-PM.jpeg\" alt=\"Wallfahrtskapelle der Gottesmutter in Caracas\" width=\"754\" height=\"1008\" \/><\/p>\n<h3>Auf der Suche nach dem Bildstock in Caracas<\/h3>\n<p>Die Sehnsucht war sehr gro\u00df, und so machten sich Gonz\u00e1lez und Antonio auf die Suche nach diesem Schatz, der f\u00fcr sie einen Wallfahrtsort darstellte, an dem die Gottesmutter darauf wartete, ihre Gnaden neu auszusch\u00fctten und dem Wachstum Sch\u00f6nstatts in Venezuela neuen Schwung zu verleihen. Sie machten sich auf die Suche nach diesem kleinen Ort, an dem die Gottesmutter zu finden war. Auf diese Weise gelangten sie zu einem Gesch\u00e4ft in Dos Caminos in Caracas. Sie erfuhren, dass ein Anrainer bereits von einem Wallfahrtsort im Humboldt-Park in La Castellana erz\u00e4hlte. Am Fu\u00dfe des ikonischen Berges, dem Wahrzeichen der Stadt Caracas, befand es sich.<\/p>\n<p>Am n\u00e4chsten Tag wurde Antonio Nodas Herz von einem \u00fcbernat\u00fcrlichen Impuls ber\u00fchrt, der ihn dazu brachte, aufzustehen und den Wallfahrtsort zu suchen. Nach langem Suchen kamen er und seine Frau zu einem Sportpark, wo die Gottesmutter endlich zu finden war.<\/p>\n<p>Antonio berichtet von dieser Begegnung:<\/p>\n<blockquote><p>&#8222;Es war eine so gro\u00dfe Freude in unseren Herzen, dass wir weinten und vor dem Bildstock knieten. Er war nach all der Zeit in einem sehr schlechten Zustand. Es tat uns weh, die Gottesmutter in einem solchen Zustand zu sehen. Wir fingen an, sie ein wenig zu s\u00e4ubern, und dann machten wir einige Fotos davon und schickten sie an unsere Sch\u00f6nstattgruppe in Costa Rica, an Bruder Angel Pacheco Bastidas und seine Frau Aurimar Gonz\u00e1lez. Das war unsere sch\u00f6ne Begegnung mit der Gottesmutter.\u201c<\/p><\/blockquote>\n<p>In den letzten Wochen haben Janet und Antonio ihr Apostolat fortgesetzt, um die Gottesmutter in der Pfarrei St. Johannes Eudes bekannt zu machen, wo viele Gl\u00e4ubige bereits mit Hingabe zu ihr beten. Sie wollen viel <a href=\"https:\/\/schoenstatt.com\/de\/spiritualitaet\/das-liebesbuendnis\/gnadenkapital\/\">Gnadenkapital<\/a> anbieten, damit dieses Wiederaufleben der Bewegung in Venezuela diese sch\u00f6ne Nation mit Segen erf\u00fcllt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Paar suchte einen alten MTA-Bildstock<\/p>\n","protected":false},"author":3,"featured_media":18969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195,678],"tags":[1252,930],"class_list":["post-18987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amerika-de","category-lander-de","tag-bildstock-de","tag-schonstatt-venezuela-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas - Schoenstatt<\/title>\n<meta name=\"description\" content=\"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas\" \/>\n<meta property=\"og:description\" content=\"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/\" \/>\n<meta property=\"og:site_name\" content=\"Schoenstatt\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T19:31:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T15:47:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"754\" \/>\n\t<meta property=\"og:image:height\" content=\"1008\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karen Bueno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karen Bueno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/\"},\"author\":{\"name\":\"Karen Bueno\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\"},\"headline\":\"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas\",\"datePublished\":\"2021-09-21T19:31:46+00:00\",\"dateModified\":\"2025-08-18T15:47:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg\",\"keywords\":[\"Bildstock\",\"Sch\u00f6nstatt Venezuela\"],\"articleSection\":[\"Amerika\",\"L\u00e4nder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/\",\"name\":\"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas - Schoenstatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg\",\"datePublished\":\"2021-09-21T19:31:46+00:00\",\"dateModified\":\"2025-08-18T15:47:27+00:00\",\"description\":\"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg\",\"width\":754,\"height\":1008,\"caption\":\"Schoenstatt Wayside Shrine in Venezuela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"name\":\"Schoenstatt\",\"description\":\"Apostolic Movement\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#organization\",\"name\":\"Schoenstatt\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/schoenstatt.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-schoenstatt-white-696x696-1.png\",\"width\":696,\"height\":694,\"caption\":\"Schoenstatt\"},\"image\":{\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/#\\\/schema\\\/person\\\/5158877ad4acae98b34daaeef2a1ce6e\",\"name\":\"Karen Bueno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g\",\"caption\":\"Karen Bueno\"},\"url\":\"https:\\\/\\\/schoenstatt.com\\\/de\\\/author\\\/karen-bueno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas - Schoenstatt","description":"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/","og_locale":"de_DE","og_type":"article","og_title":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas","og_description":"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.","og_url":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/","og_site_name":"Schoenstatt","article_published_time":"2021-09-21T19:31:46+00:00","article_modified_time":"2025-08-18T15:47:27+00:00","og_image":[{"width":754,"height":1008,"url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg","type":"image\/jpeg"}],"author":"Karen Bueno","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Karen Bueno","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#article","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/"},"author":{"name":"Karen Bueno","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e"},"headline":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas","datePublished":"2021-09-21T19:31:46+00:00","dateModified":"2025-08-18T15:47:27+00:00","mainEntityOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/"},"wordCount":544,"publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg","keywords":["Bildstock","Sch\u00f6nstatt Venezuela"],"articleSection":["Amerika","L\u00e4nder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/","url":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/","name":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas - Schoenstatt","isPartOf":{"@id":"https:\/\/schoenstatt.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#primaryimage"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg","datePublished":"2021-09-21T19:31:46+00:00","dateModified":"2025-08-18T15:47:27+00:00","description":"Nach der Teilnahme an einem Sch\u00f6nstatt-Einf\u00fchrungskurs folgen Janeth und Antonio den Spuren zu einer alten Wallfahrtskapelle in Caracas.","breadcrumb":{"@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#primaryimage","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-09-15-at-5.15.11-PM-3.jpeg","width":754,"height":1008,"caption":"Schoenstatt Wayside Shrine in Venezuela"},{"@type":"BreadcrumbList","@id":"https:\/\/schoenstatt.com\/de\/unser-schatz-die-wallfahrtskapelle-der-gottesmutter-in-caracas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/schoenstatt.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Unser Schatz: Die Wallfahrtskapelle der Gottesmutter in Caracas"}]},{"@type":"WebSite","@id":"https:\/\/schoenstatt.com\/de\/#website","url":"https:\/\/schoenstatt.com\/de\/","name":"Schoenstatt","description":"Apostolic Movement","publisher":{"@id":"https:\/\/schoenstatt.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoenstatt.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoenstatt.com\/de\/#organization","name":"Schoenstatt","url":"https:\/\/schoenstatt.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","contentUrl":"https:\/\/schoenstatt.com\/wp-content\/uploads\/2025\/04\/logo-schoenstatt-white-696x696-1.png","width":696,"height":694,"caption":"Schoenstatt"},"image":{"@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/schoenstatt.com\/de\/#\/schema\/person\/5158877ad4acae98b34daaeef2a1ce6e","name":"Karen Bueno","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9f4b823873154269d2b2130f195f6d41037dd0d7fc5f3cacb5c846bae70d66b?s=96&d=mm&r=g","caption":"Karen Bueno"},"url":"https:\/\/schoenstatt.com\/de\/author\/karen-bueno\/"}]}},"_links":{"self":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/18987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/comments?post=18987"}],"version-history":[{"count":1,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/18987\/revisions"}],"predecessor-version":[{"id":44692,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/posts\/18987\/revisions\/44692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media\/18969"}],"wp:attachment":[{"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/media?parent=18987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/categories?post=18987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoenstatt.com\/de\/wp-json\/wp\/v2\/tags?post=18987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}